{"id":6858,"count":0,"description":"<h2 class=\"smc-custom-heading\">Il contatto con la strada ne decide il carattere.<\/h2>\nCerchi e pneumatici sono tra i dettagli che cambiano immediatamente il carattere di un veicolo. Dimensioni, larghezza, offset, profilo e materiale non determinano solo l'estetica \u2013 decidono quanto un modello scale risulti autentico. \n\nSu ScaleMonkey trovi pneumatici e cerchi selezionati per progetti di modellismo automobilistico ambiziosi. Dai design classici alle ruote performance moderne, dalle combinazioni pronte ai componenti per configurazioni individuali. \n\nNon si tratta di mettere una ruota qualsiasi sotto la carrozzeria. Si tratta della giusta combinazione di proporzioni, fedelt\u00e0 ai dettagli e funzione. Perch\u00e9 proprio dalle ruote si capisce subito se un modello \u00e8 costruito con coerenza \u2013 o se ne ha solo l'aspetto.  \n\n<strong>Per modelli dove conta anche l'ultimo millimetro.<\/strong>","link":"https:\/\/www.scalemonkey.com\/it-ch\/store\/model-building\/model-cars\/wheels-tires\/","name":"Cerchi &amp; Pneumatici","slug":"wheels-tires","taxonomy":"product_cat","parent":6843,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cerchi &amp; Pneumatici-Archiv | scalemonkey.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.scalemonkey.com\/it-ch\/store\/model-building\/model-cars\/wheels-tires\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cerchi &amp; Pneumatici-Archiv | scalemonkey.com\" \/>\n<meta property=\"og:description\" content=\"Il contatto con la strada ne decide il carattere. Cerchi e pneumatici sono tra i dettagli che cambiano immediatamente il carattere di un veicolo. Dimensioni, larghezza, offset, profilo e materiale non determinano solo l&#8217;estetica \u2013 decidono quanto un modello scale risulti autentico. Su ScaleMonkey trovi pneumatici e cerchi selezionati per progetti di modellismo automobilistico ambiziosi. Dai design classici alle ruote performance moderne, dalle combinazioni pronte ai componenti per configurazioni individuali. Non si tratta di mettere una ruota qualsiasi sotto la carrozzeria. Si tratta della giusta combinazione di proporzioni, fedelt\u00e0 ai dettagli e funzione. Perch\u00e9 proprio dalle ruote si capisce subito se un modello \u00e8 costruito con coerenza \u2013 o se ne ha solo l&#8217;aspetto.  Per modelli dove conta anche l&#8217;ultimo millimetro.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.scalemonkey.com\/it-ch\/store\/model-building\/model-cars\/wheels-tires\/\" \/>\n<meta property=\"og:site_name\" content=\"scalemonkey.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/it-ch\\\/store\\\/model-building\\\/model-cars\\\/wheels-tires\\\/\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/it-ch\\\/store\\\/model-building\\\/model-cars\\\/wheels-tires\\\/\",\"name\":\"Cerchi &amp; Pneumatici-Archiv | scalemonkey.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/it-ch\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/it-ch\\\/store\\\/model-building\\\/model-cars\\\/wheels-tires\\\/#breadcrumb\"},\"inLanguage\":\"it-CH\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/it-ch\\\/store\\\/model-building\\\/model-cars\\\/wheels-tires\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Start\",\"item\":\"https:\\\/\\\/www.scalemonkey.com\\\/it-ch\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cerchi &amp; Pneumatici\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/it-ch\\\/#website\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/it-ch\\\/\",\"name\":\"ScaleMonkey\",\"description\":\"Anspruchsvoller RC-Modellbau, eigene Baus\u00e4tze, Rolling-Chassis, Upgrades und Zubeh\u00f6r.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/it-ch\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.scalemonkey.com\\\/it-ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-CH\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/it-ch\\\/#organization\",\"name\":\"ScaleMonkey\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/it-ch\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-CH\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/it-ch\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/ScaleMonkey-mail.jpg\",\"contentUrl\":\"https:\\\/\\\/www.scalemonkey.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/ScaleMonkey-mail.jpg\",\"width\":591,\"height\":591,\"caption\":\"ScaleMonkey\"},\"image\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/it-ch\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/scalemonkey\\\/\",\"https:\\\/\\\/www.instagram.com\\\/scalemonkey\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@scalemonkeyofficial\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cerchi &amp; Pneumatici-Archiv | scalemonkey.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.scalemonkey.com\/it-ch\/store\/model-building\/model-cars\/wheels-tires\/","og_locale":"it_IT","og_type":"article","og_title":"Cerchi &amp; Pneumatici-Archiv | scalemonkey.com","og_description":"Il contatto con la strada ne decide il carattere. Cerchi e pneumatici sono tra i dettagli che cambiano immediatamente il carattere di un veicolo. Dimensioni, larghezza, offset, profilo e materiale non determinano solo l&#8217;estetica \u2013 decidono quanto un modello scale risulti autentico. Su ScaleMonkey trovi pneumatici e cerchi selezionati per progetti di modellismo automobilistico ambiziosi. Dai design classici alle ruote performance moderne, dalle combinazioni pronte ai componenti per configurazioni individuali. Non si tratta di mettere una ruota qualsiasi sotto la carrozzeria. Si tratta della giusta combinazione di proporzioni, fedelt\u00e0 ai dettagli e funzione. Perch\u00e9 proprio dalle ruote si capisce subito se un modello \u00e8 costruito con coerenza \u2013 o se ne ha solo l&#8217;aspetto.  Per modelli dove conta anche l&#8217;ultimo millimetro.","og_url":"https:\/\/www.scalemonkey.com\/it-ch\/store\/model-building\/model-cars\/wheels-tires\/","og_site_name":"scalemonkey.com","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.scalemonkey.com\/it-ch\/store\/model-building\/model-cars\/wheels-tires\/","url":"https:\/\/www.scalemonkey.com\/it-ch\/store\/model-building\/model-cars\/wheels-tires\/","name":"Cerchi &amp; Pneumatici-Archiv | scalemonkey.com","isPartOf":{"@id":"https:\/\/www.scalemonkey.com\/it-ch\/#website"},"breadcrumb":{"@id":"https:\/\/www.scalemonkey.com\/it-ch\/store\/model-building\/model-cars\/wheels-tires\/#breadcrumb"},"inLanguage":"it-CH"},{"@type":"BreadcrumbList","@id":"https:\/\/www.scalemonkey.com\/it-ch\/store\/model-building\/model-cars\/wheels-tires\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Start","item":"https:\/\/www.scalemonkey.com\/it-ch\/home\/"},{"@type":"ListItem","position":2,"name":"Cerchi &amp; Pneumatici"}]},{"@type":"WebSite","@id":"https:\/\/www.scalemonkey.com\/it-ch\/#website","url":"https:\/\/www.scalemonkey.com\/it-ch\/","name":"ScaleMonkey","description":"Anspruchsvoller RC-Modellbau, eigene Baus\u00e4tze, Rolling-Chassis, Upgrades und Zubeh\u00f6r.","publisher":{"@id":"https:\/\/www.scalemonkey.com\/it-ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.scalemonkey.com\/it-ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-CH"},{"@type":"Organization","@id":"https:\/\/www.scalemonkey.com\/it-ch\/#organization","name":"ScaleMonkey","url":"https:\/\/www.scalemonkey.com\/it-ch\/","logo":{"@type":"ImageObject","inLanguage":"it-CH","@id":"https:\/\/www.scalemonkey.com\/it-ch\/#\/schema\/logo\/image\/","url":"https:\/\/www.scalemonkey.com\/wp-content\/uploads\/2026\/08\/ScaleMonkey-mail.jpg","contentUrl":"https:\/\/www.scalemonkey.com\/wp-content\/uploads\/2026\/08\/ScaleMonkey-mail.jpg","width":591,"height":591,"caption":"ScaleMonkey"},"image":{"@id":"https:\/\/www.scalemonkey.com\/it-ch\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/scalemonkey\/","https:\/\/www.instagram.com\/scalemonkey\/","https:\/\/www.youtube.com\/@scalemonkeyofficial\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.scalemonkey.com\/it-ch\/wp-json\/wp\/v2\/product_cat\/6858","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.scalemonkey.com\/it-ch\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.scalemonkey.com\/it-ch\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/www.scalemonkey.com\/it-ch\/wp-json\/wp\/v2\/product_cat\/6843"}],"wp:post_type":[{"href":"https:\/\/www.scalemonkey.com\/it-ch\/wp-json\/wp\/v2\/product?product_cat=6858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}