{"id":6840,"count":5,"description":"<h2 class=\"smc-custom-heading\">Servi 20 mm<span class=\"smc-newline-separator\">Quando contano forza e precisione<\/span><\/h2>\nI servi da 20 mm sono pensati per modelli scale dove dimensioni compatte e alte riserve di potenza devono coesistere. Offrono pi\u00f9 spazio per componenti di trasmissione robusti e sono quindi particolarmente adatti per applicazioni dove sterzo e meccanica sono esposti a sollecitazioni sensibili. \n\nScaleMonkey offre servi da 20 mm selezionati per modelli RC esigenti \u2013 dai potenti sterzi fino alle meccaniche di cambio e funzioni speciali. Fondamentale \u00e8 la giusta combinazione di coppia, velocit\u00e0, precisione e resistenza. \n\nIn modelli pesanti, con grandi pneumatici o telai elaborati, un servo deve saper fare di pi\u00f9 che eseguire semplicemente un comando. Deve attuare il movimento in modo riproducibile e affidabile \u2013 anche quando la meccanica \u00e8 sotto sforzo. \n\nPer questo non scegliamo la tecnologia dei servi solo in base alla dimensione. L'importante \u00e8 ci\u00f2 che serve effettivamente nel modello finito. \n\n<strong>Forza quando serve. Precisione quando conta. <\/strong>","link":"https:\/\/www.scalemonkey.com\/it-ch\/store\/model-building\/rc-accessories\/servos\/20mm\/","name":"Servi \u2013 20 mm","slug":"20mm","taxonomy":"product_cat","parent":6837,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Servi \u2013 20 mm-Archiv | scalemonkey.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.scalemonkey.com\/it-ch\/store\/model-building\/rc-accessories\/servos\/20mm\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Servi \u2013 20 mm-Archiv | scalemonkey.com\" \/>\n<meta property=\"og:description\" content=\"Servi 20 mmQuando contano forza e precisione I servi da 20 mm sono pensati per modelli scale dove dimensioni compatte e alte riserve di potenza devono coesistere. Offrono pi\u00f9 spazio per componenti di trasmissione robusti e sono quindi particolarmente adatti per applicazioni dove sterzo e meccanica sono esposti a sollecitazioni sensibili. ScaleMonkey offre servi da 20 mm selezionati per modelli RC esigenti \u2013 dai potenti sterzi fino alle meccaniche di cambio e funzioni speciali. Fondamentale \u00e8 la giusta combinazione di coppia, velocit\u00e0, precisione e resistenza. In modelli pesanti, con grandi pneumatici o telai elaborati, un servo deve saper fare di pi\u00f9 che eseguire semplicemente un comando. Deve attuare il movimento in modo riproducibile e affidabile \u2013 anche quando la meccanica \u00e8 sotto sforzo. Per questo non scegliamo la tecnologia dei servi solo in base alla dimensione. L&#8217;importante \u00e8 ci\u00f2 che serve effettivamente nel modello finito. Forza quando serve. Precisione quando conta.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.scalemonkey.com\/it-ch\/store\/model-building\/rc-accessories\/servos\/20mm\/\" \/>\n<meta property=\"og:site_name\" content=\"scalemonkey.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/it-ch\\\/store\\\/model-building\\\/rc-accessories\\\/servos\\\/20mm\\\/\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/it-ch\\\/store\\\/model-building\\\/rc-accessories\\\/servos\\\/20mm\\\/\",\"name\":\"Servi \u2013 20 mm-Archiv | scalemonkey.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/it-ch\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/it-ch\\\/store\\\/model-building\\\/rc-accessories\\\/servos\\\/20mm\\\/#breadcrumb\"},\"inLanguage\":\"it-CH\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/it-ch\\\/store\\\/model-building\\\/rc-accessories\\\/servos\\\/20mm\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Start\",\"item\":\"https:\\\/\\\/www.scalemonkey.com\\\/it-ch\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Servi \u2013 20 mm\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/it-ch\\\/#website\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/it-ch\\\/\",\"name\":\"ScaleMonkey\",\"description\":\"Anspruchsvoller RC-Modellbau, eigene Baus\u00e4tze, Rolling-Chassis, Upgrades und Zubeh\u00f6r.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/it-ch\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.scalemonkey.com\\\/it-ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-CH\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/it-ch\\\/#organization\",\"name\":\"ScaleMonkey\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/it-ch\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-CH\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/it-ch\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/ScaleMonkey-mail.jpg\",\"contentUrl\":\"https:\\\/\\\/www.scalemonkey.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/ScaleMonkey-mail.jpg\",\"width\":591,\"height\":591,\"caption\":\"ScaleMonkey\"},\"image\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/it-ch\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/scalemonkey\\\/\",\"https:\\\/\\\/www.instagram.com\\\/scalemonkey\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@scalemonkeyofficial\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Servi \u2013 20 mm-Archiv | scalemonkey.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.scalemonkey.com\/it-ch\/store\/model-building\/rc-accessories\/servos\/20mm\/","og_locale":"it_IT","og_type":"article","og_title":"Servi \u2013 20 mm-Archiv | scalemonkey.com","og_description":"Servi 20 mmQuando contano forza e precisione I servi da 20 mm sono pensati per modelli scale dove dimensioni compatte e alte riserve di potenza devono coesistere. Offrono pi\u00f9 spazio per componenti di trasmissione robusti e sono quindi particolarmente adatti per applicazioni dove sterzo e meccanica sono esposti a sollecitazioni sensibili. ScaleMonkey offre servi da 20 mm selezionati per modelli RC esigenti \u2013 dai potenti sterzi fino alle meccaniche di cambio e funzioni speciali. Fondamentale \u00e8 la giusta combinazione di coppia, velocit\u00e0, precisione e resistenza. In modelli pesanti, con grandi pneumatici o telai elaborati, un servo deve saper fare di pi\u00f9 che eseguire semplicemente un comando. Deve attuare il movimento in modo riproducibile e affidabile \u2013 anche quando la meccanica \u00e8 sotto sforzo. Per questo non scegliamo la tecnologia dei servi solo in base alla dimensione. L&#8217;importante \u00e8 ci\u00f2 che serve effettivamente nel modello finito. Forza quando serve. Precisione quando conta.","og_url":"https:\/\/www.scalemonkey.com\/it-ch\/store\/model-building\/rc-accessories\/servos\/20mm\/","og_site_name":"scalemonkey.com","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.scalemonkey.com\/it-ch\/store\/model-building\/rc-accessories\/servos\/20mm\/","url":"https:\/\/www.scalemonkey.com\/it-ch\/store\/model-building\/rc-accessories\/servos\/20mm\/","name":"Servi \u2013 20 mm-Archiv | scalemonkey.com","isPartOf":{"@id":"https:\/\/www.scalemonkey.com\/it-ch\/#website"},"breadcrumb":{"@id":"https:\/\/www.scalemonkey.com\/it-ch\/store\/model-building\/rc-accessories\/servos\/20mm\/#breadcrumb"},"inLanguage":"it-CH"},{"@type":"BreadcrumbList","@id":"https:\/\/www.scalemonkey.com\/it-ch\/store\/model-building\/rc-accessories\/servos\/20mm\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Start","item":"https:\/\/www.scalemonkey.com\/it-ch\/home\/"},{"@type":"ListItem","position":2,"name":"Servi \u2013 20 mm"}]},{"@type":"WebSite","@id":"https:\/\/www.scalemonkey.com\/it-ch\/#website","url":"https:\/\/www.scalemonkey.com\/it-ch\/","name":"ScaleMonkey","description":"Anspruchsvoller RC-Modellbau, eigene Baus\u00e4tze, Rolling-Chassis, Upgrades und Zubeh\u00f6r.","publisher":{"@id":"https:\/\/www.scalemonkey.com\/it-ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.scalemonkey.com\/it-ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-CH"},{"@type":"Organization","@id":"https:\/\/www.scalemonkey.com\/it-ch\/#organization","name":"ScaleMonkey","url":"https:\/\/www.scalemonkey.com\/it-ch\/","logo":{"@type":"ImageObject","inLanguage":"it-CH","@id":"https:\/\/www.scalemonkey.com\/it-ch\/#\/schema\/logo\/image\/","url":"https:\/\/www.scalemonkey.com\/wp-content\/uploads\/2026\/08\/ScaleMonkey-mail.jpg","contentUrl":"https:\/\/www.scalemonkey.com\/wp-content\/uploads\/2026\/08\/ScaleMonkey-mail.jpg","width":591,"height":591,"caption":"ScaleMonkey"},"image":{"@id":"https:\/\/www.scalemonkey.com\/it-ch\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/scalemonkey\/","https:\/\/www.instagram.com\/scalemonkey\/","https:\/\/www.youtube.com\/@scalemonkeyofficial\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.scalemonkey.com\/it-ch\/wp-json\/wp\/v2\/product_cat\/6840","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.scalemonkey.com\/it-ch\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.scalemonkey.com\/it-ch\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/www.scalemonkey.com\/it-ch\/wp-json\/wp\/v2\/product_cat\/6837"}],"wp:post_type":[{"href":"https:\/\/www.scalemonkey.com\/it-ch\/wp-json\/wp\/v2\/product?product_cat=6840"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}