{"id":7044,"count":1,"description":"<h2 class=\"smc-custom-heading\">Servos 10\u201314 mm<span class=\"smc-newline-separator\">La pr\u00e9cision dans un espace restreint<\/span><\/h2>\nQuand l'espace vient \u00e0 manquer, chaque millim\u00e8tre compte. Les servos d'une hauteur de 10\u201314 mm sont int\u00e9ressants pour les mod\u00e8les scale o\u00f9 les servos standards classiques sont tout simplement trop volumineux. \n\nScaleMonkey propose une s\u00e9lection de micro-servos et de servos low-profile pour les situations d'installation compactes et les mod\u00e8les scale exigeants. Malgr\u00e9 leurs dimensions r\u00e9duites, la force, la pr\u00e9cision et la fiabilit\u00e9 doivent correspondre au domaine d'utilisation respectif. \n\nQu'ils soient cach\u00e9s dans le ch\u00e2ssis, int\u00e9gr\u00e9s dans une direction filigrane ou pour une fonction sp\u00e9ciale : la bonne taille de servo lib\u00e8re de l'espace pour la construction et la fid\u00e9lit\u00e9 des d\u00e9tails, sans faire de compromis inutiles sur la fonction.\n\n<strong>Construction compacte. Utilisation pr\u00e9cise. <\/strong>","link":"https:\/\/www.scalemonkey.com\/fr-ch\/store\/model-building\/rc-accessories\/servos\/servos-10-14mm\/","name":"Servos \u2013 10-14 mm","slug":"servos-10-14mm","taxonomy":"product_cat","parent":7029,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Servos \u2013 10-14 mm-Archiv | scalemonkey.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.scalemonkey.com\/fr-ch\/store\/model-building\/rc-accessories\/servos\/servos-10-14mm\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Servos \u2013 10-14 mm-Archiv | scalemonkey.com\" \/>\n<meta property=\"og:description\" content=\"Servos 10\u201314 mmLa pr\u00e9cision dans un espace restreint Quand l&#8217;espace vient \u00e0 manquer, chaque millim\u00e8tre compte. Les servos d&#8217;une hauteur de 10\u201314 mm sont int\u00e9ressants pour les mod\u00e8les scale o\u00f9 les servos standards classiques sont tout simplement trop volumineux. ScaleMonkey propose une s\u00e9lection de micro-servos et de servos low-profile pour les situations d&#8217;installation compactes et les mod\u00e8les scale exigeants. Malgr\u00e9 leurs dimensions r\u00e9duites, la force, la pr\u00e9cision et la fiabilit\u00e9 doivent correspondre au domaine d&#8217;utilisation respectif. Qu&#8217;ils soient cach\u00e9s dans le ch\u00e2ssis, int\u00e9gr\u00e9s dans une direction filigrane ou pour une fonction sp\u00e9ciale : la bonne taille de servo lib\u00e8re de l&#8217;espace pour la construction et la fid\u00e9lit\u00e9 des d\u00e9tails, sans faire de compromis inutiles sur la fonction. Construction compacte. Utilisation pr\u00e9cise.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.scalemonkey.com\/fr-ch\/store\/model-building\/rc-accessories\/servos\/servos-10-14mm\/\" \/>\n<meta property=\"og:site_name\" content=\"scalemonkey.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-ch\\\/store\\\/model-building\\\/rc-accessories\\\/servos\\\/servos-10-14mm\\\/\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-ch\\\/store\\\/model-building\\\/rc-accessories\\\/servos\\\/servos-10-14mm\\\/\",\"name\":\"Servos \u2013 10-14 mm-Archiv | scalemonkey.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-ch\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-ch\\\/store\\\/model-building\\\/rc-accessories\\\/servos\\\/servos-10-14mm\\\/#breadcrumb\"},\"inLanguage\":\"fr-CH\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-ch\\\/store\\\/model-building\\\/rc-accessories\\\/servos\\\/servos-10-14mm\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Start\",\"item\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-ch\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Servos \u2013 10-14 mm\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-ch\\\/#website\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-ch\\\/\",\"name\":\"ScaleMonkey\",\"description\":\"Anspruchsvoller RC-Modellbau, eigene Baus\u00e4tze, Rolling-Chassis, Upgrades und Zubeh\u00f6r.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-ch\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CH\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-ch\\\/#organization\",\"name\":\"ScaleMonkey\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-ch\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CH\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-ch\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/ScaleMonkey-mail.jpg\",\"contentUrl\":\"https:\\\/\\\/www.scalemonkey.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/ScaleMonkey-mail.jpg\",\"width\":591,\"height\":591,\"caption\":\"ScaleMonkey\"},\"image\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-ch\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/scalemonkey\\\/\",\"https:\\\/\\\/www.instagram.com\\\/scalemonkey\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@scalemonkeyofficial\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Servos \u2013 10-14 mm-Archiv | scalemonkey.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.scalemonkey.com\/fr-ch\/store\/model-building\/rc-accessories\/servos\/servos-10-14mm\/","og_locale":"fr_FR","og_type":"article","og_title":"Servos \u2013 10-14 mm-Archiv | scalemonkey.com","og_description":"Servos 10\u201314 mmLa pr\u00e9cision dans un espace restreint Quand l&#8217;espace vient \u00e0 manquer, chaque millim\u00e8tre compte. Les servos d&#8217;une hauteur de 10\u201314 mm sont int\u00e9ressants pour les mod\u00e8les scale o\u00f9 les servos standards classiques sont tout simplement trop volumineux. ScaleMonkey propose une s\u00e9lection de micro-servos et de servos low-profile pour les situations d&#8217;installation compactes et les mod\u00e8les scale exigeants. Malgr\u00e9 leurs dimensions r\u00e9duites, la force, la pr\u00e9cision et la fiabilit\u00e9 doivent correspondre au domaine d&#8217;utilisation respectif. Qu&#8217;ils soient cach\u00e9s dans le ch\u00e2ssis, int\u00e9gr\u00e9s dans une direction filigrane ou pour une fonction sp\u00e9ciale : la bonne taille de servo lib\u00e8re de l&#8217;espace pour la construction et la fid\u00e9lit\u00e9 des d\u00e9tails, sans faire de compromis inutiles sur la fonction. Construction compacte. Utilisation pr\u00e9cise.","og_url":"https:\/\/www.scalemonkey.com\/fr-ch\/store\/model-building\/rc-accessories\/servos\/servos-10-14mm\/","og_site_name":"scalemonkey.com","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.scalemonkey.com\/fr-ch\/store\/model-building\/rc-accessories\/servos\/servos-10-14mm\/","url":"https:\/\/www.scalemonkey.com\/fr-ch\/store\/model-building\/rc-accessories\/servos\/servos-10-14mm\/","name":"Servos \u2013 10-14 mm-Archiv | scalemonkey.com","isPartOf":{"@id":"https:\/\/www.scalemonkey.com\/fr-ch\/#website"},"breadcrumb":{"@id":"https:\/\/www.scalemonkey.com\/fr-ch\/store\/model-building\/rc-accessories\/servos\/servos-10-14mm\/#breadcrumb"},"inLanguage":"fr-CH"},{"@type":"BreadcrumbList","@id":"https:\/\/www.scalemonkey.com\/fr-ch\/store\/model-building\/rc-accessories\/servos\/servos-10-14mm\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Start","item":"https:\/\/www.scalemonkey.com\/fr-ch\/home\/"},{"@type":"ListItem","position":2,"name":"Servos \u2013 10-14 mm"}]},{"@type":"WebSite","@id":"https:\/\/www.scalemonkey.com\/fr-ch\/#website","url":"https:\/\/www.scalemonkey.com\/fr-ch\/","name":"ScaleMonkey","description":"Anspruchsvoller RC-Modellbau, eigene Baus\u00e4tze, Rolling-Chassis, Upgrades und Zubeh\u00f6r.","publisher":{"@id":"https:\/\/www.scalemonkey.com\/fr-ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.scalemonkey.com\/fr-ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CH"},{"@type":"Organization","@id":"https:\/\/www.scalemonkey.com\/fr-ch\/#organization","name":"ScaleMonkey","url":"https:\/\/www.scalemonkey.com\/fr-ch\/","logo":{"@type":"ImageObject","inLanguage":"fr-CH","@id":"https:\/\/www.scalemonkey.com\/fr-ch\/#\/schema\/logo\/image\/","url":"https:\/\/www.scalemonkey.com\/wp-content\/uploads\/2026\/08\/ScaleMonkey-mail.jpg","contentUrl":"https:\/\/www.scalemonkey.com\/wp-content\/uploads\/2026\/08\/ScaleMonkey-mail.jpg","width":591,"height":591,"caption":"ScaleMonkey"},"image":{"@id":"https:\/\/www.scalemonkey.com\/fr-ch\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/scalemonkey\/","https:\/\/www.instagram.com\/scalemonkey\/","https:\/\/www.youtube.com\/@scalemonkeyofficial\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.scalemonkey.com\/fr-ch\/wp-json\/wp\/v2\/product_cat\/7044","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.scalemonkey.com\/fr-ch\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.scalemonkey.com\/fr-ch\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/www.scalemonkey.com\/fr-ch\/wp-json\/wp\/v2\/product_cat\/7029"}],"wp:post_type":[{"href":"https:\/\/www.scalemonkey.com\/fr-ch\/wp-json\/wp\/v2\/product?product_cat=7044"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}