{"id":7036,"count":0,"description":"<h2 class=\"smc-custom-heading\">Plus qu'une simple mise \u00e0 niveau.<\/h2>\nUn bon mod\u00e8le fonctionne. Un mod\u00e8le exceptionnel va encore plus loin. \n\nNos pi\u00e8ces de tuning sont destin\u00e9es aux mod\u00e9listes qui ne se contentent pas du standard. Des composants et des solutions bien pens\u00e9s font \u00e9voluer de mani\u00e8re cibl\u00e9e le ch\u00e2ssis, la transmission et l'esth\u00e9tique d'un mod\u00e8le. \n\nIl ne s'agit pas d'installer le plus grand nombre de pi\u00e8ces possible. Ce qui compte, c'est leur effet \u2013 technique, fonctionnel et visuel. C'est pourquoi nous veillons \u00e0 la qualit\u00e9, \u00e0 l'ajustement et \u00e0 l'utilit\u00e9 r\u00e9elle sur le v\u00e9hicule.  \n\nBeaucoup de nos solutions sont n\u00e9es de la pratique de notre propre mod\u00e9lisme et sont d\u00e9velopp\u00e9es et fabriqu\u00e9es en Allemagne. D'autres proviennent de fabricants dont les produits r\u00e9pondent \u00e0 nos exigences. \n\n<strong>Le standard est le point de d\u00e9part. Le reste d\u00e9pend de toi. <\/strong>","link":"https:\/\/www.scalemonkey.com\/fr-ch\/store\/model-building\/model-cars\/upgrade-parts\/","name":"Pi\u00e8ces de tuning","slug":"upgrade-parts","taxonomy":"product_cat","parent":7035,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pi\u00e8ces de tuning-Archiv | scalemonkey.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.scalemonkey.com\/fr-ch\/store\/model-building\/model-cars\/upgrade-parts\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pi\u00e8ces de tuning-Archiv | scalemonkey.com\" \/>\n<meta property=\"og:description\" content=\"Plus qu&#8217;une simple mise \u00e0 niveau. Un bon mod\u00e8le fonctionne. Un mod\u00e8le exceptionnel va encore plus loin. Nos pi\u00e8ces de tuning sont destin\u00e9es aux mod\u00e9listes qui ne se contentent pas du standard. Des composants et des solutions bien pens\u00e9s font \u00e9voluer de mani\u00e8re cibl\u00e9e le ch\u00e2ssis, la transmission et l&#8217;esth\u00e9tique d&#8217;un mod\u00e8le. Il ne s&#8217;agit pas d&#8217;installer le plus grand nombre de pi\u00e8ces possible. Ce qui compte, c&#8217;est leur effet \u2013 technique, fonctionnel et visuel. C&#8217;est pourquoi nous veillons \u00e0 la qualit\u00e9, \u00e0 l&#8217;ajustement et \u00e0 l&#8217;utilit\u00e9 r\u00e9elle sur le v\u00e9hicule.  Beaucoup de nos solutions sont n\u00e9es de la pratique de notre propre mod\u00e9lisme et sont d\u00e9velopp\u00e9es et fabriqu\u00e9es en Allemagne. D&#8217;autres proviennent de fabricants dont les produits r\u00e9pondent \u00e0 nos exigences. Le standard est le point de d\u00e9part. Le reste d\u00e9pend de toi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.scalemonkey.com\/fr-ch\/store\/model-building\/model-cars\/upgrade-parts\/\" \/>\n<meta property=\"og:site_name\" content=\"scalemonkey.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-ch\\\/store\\\/model-building\\\/model-cars\\\/upgrade-parts\\\/\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-ch\\\/store\\\/model-building\\\/model-cars\\\/upgrade-parts\\\/\",\"name\":\"Pi\u00e8ces de tuning-Archiv | scalemonkey.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-ch\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-ch\\\/store\\\/model-building\\\/model-cars\\\/upgrade-parts\\\/#breadcrumb\"},\"inLanguage\":\"fr-CH\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-ch\\\/store\\\/model-building\\\/model-cars\\\/upgrade-parts\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Start\",\"item\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-ch\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pi\u00e8ces de tuning\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-ch\\\/#website\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-ch\\\/\",\"name\":\"ScaleMonkey\",\"description\":\"Anspruchsvoller RC-Modellbau, eigene Baus\u00e4tze, Rolling-Chassis, Upgrades und Zubeh\u00f6r.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-ch\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CH\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-ch\\\/#organization\",\"name\":\"ScaleMonkey\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-ch\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CH\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-ch\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/ScaleMonkey-mail.jpg\",\"contentUrl\":\"https:\\\/\\\/www.scalemonkey.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/ScaleMonkey-mail.jpg\",\"width\":591,\"height\":591,\"caption\":\"ScaleMonkey\"},\"image\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-ch\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/scalemonkey\\\/\",\"https:\\\/\\\/www.instagram.com\\\/scalemonkey\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@scalemonkeyofficial\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pi\u00e8ces de tuning-Archiv | scalemonkey.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.scalemonkey.com\/fr-ch\/store\/model-building\/model-cars\/upgrade-parts\/","og_locale":"fr_FR","og_type":"article","og_title":"Pi\u00e8ces de tuning-Archiv | scalemonkey.com","og_description":"Plus qu&#8217;une simple mise \u00e0 niveau. Un bon mod\u00e8le fonctionne. Un mod\u00e8le exceptionnel va encore plus loin. Nos pi\u00e8ces de tuning sont destin\u00e9es aux mod\u00e9listes qui ne se contentent pas du standard. Des composants et des solutions bien pens\u00e9s font \u00e9voluer de mani\u00e8re cibl\u00e9e le ch\u00e2ssis, la transmission et l&#8217;esth\u00e9tique d&#8217;un mod\u00e8le. Il ne s&#8217;agit pas d&#8217;installer le plus grand nombre de pi\u00e8ces possible. Ce qui compte, c&#8217;est leur effet \u2013 technique, fonctionnel et visuel. C&#8217;est pourquoi nous veillons \u00e0 la qualit\u00e9, \u00e0 l&#8217;ajustement et \u00e0 l&#8217;utilit\u00e9 r\u00e9elle sur le v\u00e9hicule.  Beaucoup de nos solutions sont n\u00e9es de la pratique de notre propre mod\u00e9lisme et sont d\u00e9velopp\u00e9es et fabriqu\u00e9es en Allemagne. D&#8217;autres proviennent de fabricants dont les produits r\u00e9pondent \u00e0 nos exigences. Le standard est le point de d\u00e9part. Le reste d\u00e9pend de toi.","og_url":"https:\/\/www.scalemonkey.com\/fr-ch\/store\/model-building\/model-cars\/upgrade-parts\/","og_site_name":"scalemonkey.com","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.scalemonkey.com\/fr-ch\/store\/model-building\/model-cars\/upgrade-parts\/","url":"https:\/\/www.scalemonkey.com\/fr-ch\/store\/model-building\/model-cars\/upgrade-parts\/","name":"Pi\u00e8ces de tuning-Archiv | scalemonkey.com","isPartOf":{"@id":"https:\/\/www.scalemonkey.com\/fr-ch\/#website"},"breadcrumb":{"@id":"https:\/\/www.scalemonkey.com\/fr-ch\/store\/model-building\/model-cars\/upgrade-parts\/#breadcrumb"},"inLanguage":"fr-CH"},{"@type":"BreadcrumbList","@id":"https:\/\/www.scalemonkey.com\/fr-ch\/store\/model-building\/model-cars\/upgrade-parts\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Start","item":"https:\/\/www.scalemonkey.com\/fr-ch\/home\/"},{"@type":"ListItem","position":2,"name":"Pi\u00e8ces de tuning"}]},{"@type":"WebSite","@id":"https:\/\/www.scalemonkey.com\/fr-ch\/#website","url":"https:\/\/www.scalemonkey.com\/fr-ch\/","name":"ScaleMonkey","description":"Anspruchsvoller RC-Modellbau, eigene Baus\u00e4tze, Rolling-Chassis, Upgrades und Zubeh\u00f6r.","publisher":{"@id":"https:\/\/www.scalemonkey.com\/fr-ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.scalemonkey.com\/fr-ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CH"},{"@type":"Organization","@id":"https:\/\/www.scalemonkey.com\/fr-ch\/#organization","name":"ScaleMonkey","url":"https:\/\/www.scalemonkey.com\/fr-ch\/","logo":{"@type":"ImageObject","inLanguage":"fr-CH","@id":"https:\/\/www.scalemonkey.com\/fr-ch\/#\/schema\/logo\/image\/","url":"https:\/\/www.scalemonkey.com\/wp-content\/uploads\/2026\/08\/ScaleMonkey-mail.jpg","contentUrl":"https:\/\/www.scalemonkey.com\/wp-content\/uploads\/2026\/08\/ScaleMonkey-mail.jpg","width":591,"height":591,"caption":"ScaleMonkey"},"image":{"@id":"https:\/\/www.scalemonkey.com\/fr-ch\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/scalemonkey\/","https:\/\/www.instagram.com\/scalemonkey\/","https:\/\/www.youtube.com\/@scalemonkeyofficial\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.scalemonkey.com\/fr-ch\/wp-json\/wp\/v2\/product_cat\/7036","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.scalemonkey.com\/fr-ch\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.scalemonkey.com\/fr-ch\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/www.scalemonkey.com\/fr-ch\/wp-json\/wp\/v2\/product_cat\/7035"}],"wp:post_type":[{"href":"https:\/\/www.scalemonkey.com\/fr-ch\/wp-json\/wp\/v2\/product?product_cat=7036"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}