{"id":7024,"count":0,"description":"<h2 class=\"smc-custom-heading\">Travail du m\u00e9tal<span class=\"smc-newline-separator\">Le contr\u00f4le sur chaque dixi\u00e8me<\/span><\/h2>\nLe m\u00e9tal exige de bons outils et un travail contr\u00f4l\u00e9. Une coupe, une ar\u00eate ou un dixi\u00e8me de mati\u00e8re en trop ne se r\u00e9cup\u00e8rent pas facilement. \n\nChez ScaleMonkey, tu trouveras des outils pour le travail du m\u00e9tal en mod\u00e9lisme. Pour limer, poncer, ajuster et retoucher des profil\u00e9s, des t\u00f4les et des composants \u2013 partout o\u00f9 la pr\u00e9cision dimensionnelle et un bon r\u00e9sultat comptent. \n\nParticuli\u00e8rement pour les constructions individuelles, l'ajustement final se fait souvent directement sur l'\u00e9tabli. Les ar\u00eates sont cass\u00e9es, les contours ajust\u00e9s, les surfaces travaill\u00e9es et les composants affin\u00e9s jusqu'\u00e0 ce que technique et esth\u00e9tique se rejoignent. \n\nCe n'est pas du gros travail du m\u00e9tal en format r\u00e9duit. C'est de l'artisanat sur de petites pi\u00e8ces. \n\n<strong>Un dixi\u00e8me peut faire la diff\u00e9rence.<\/strong>","link":"https:\/\/www.scalemonkey.com\/fr-ch\/store\/garage-tools\/metalworking\/","name":"Travail du m\u00e9tal","slug":"metalworking","taxonomy":"product_cat","parent":7013,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Travail du m\u00e9tal-Archiv | scalemonkey.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.scalemonkey.com\/fr-ch\/store\/garage-tools\/metalworking\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Travail du m\u00e9tal-Archiv | scalemonkey.com\" \/>\n<meta property=\"og:description\" content=\"Travail du m\u00e9talLe contr\u00f4le sur chaque dixi\u00e8me Le m\u00e9tal exige de bons outils et un travail contr\u00f4l\u00e9. Une coupe, une ar\u00eate ou un dixi\u00e8me de mati\u00e8re en trop ne se r\u00e9cup\u00e8rent pas facilement. Chez ScaleMonkey, tu trouveras des outils pour le travail du m\u00e9tal en mod\u00e9lisme. Pour limer, poncer, ajuster et retoucher des profil\u00e9s, des t\u00f4les et des composants \u2013 partout o\u00f9 la pr\u00e9cision dimensionnelle et un bon r\u00e9sultat comptent. Particuli\u00e8rement pour les constructions individuelles, l&#8217;ajustement final se fait souvent directement sur l&#8217;\u00e9tabli. Les ar\u00eates sont cass\u00e9es, les contours ajust\u00e9s, les surfaces travaill\u00e9es et les composants affin\u00e9s jusqu&#8217;\u00e0 ce que technique et esth\u00e9tique se rejoignent. Ce n&#8217;est pas du gros travail du m\u00e9tal en format r\u00e9duit. C&#8217;est de l&#8217;artisanat sur de petites pi\u00e8ces. Un dixi\u00e8me peut faire la diff\u00e9rence.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.scalemonkey.com\/fr-ch\/store\/garage-tools\/metalworking\/\" \/>\n<meta property=\"og:site_name\" content=\"scalemonkey.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-ch\\\/store\\\/garage-tools\\\/metalworking\\\/\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-ch\\\/store\\\/garage-tools\\\/metalworking\\\/\",\"name\":\"Travail du m\u00e9tal-Archiv | scalemonkey.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-ch\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-ch\\\/store\\\/garage-tools\\\/metalworking\\\/#breadcrumb\"},\"inLanguage\":\"fr-CH\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-ch\\\/store\\\/garage-tools\\\/metalworking\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Start\",\"item\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-ch\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Travail du m\u00e9tal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-ch\\\/#website\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-ch\\\/\",\"name\":\"ScaleMonkey\",\"description\":\"Anspruchsvoller RC-Modellbau, eigene Baus\u00e4tze, Rolling-Chassis, Upgrades und Zubeh\u00f6r.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-ch\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CH\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-ch\\\/#organization\",\"name\":\"ScaleMonkey\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-ch\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CH\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-ch\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/ScaleMonkey-mail.jpg\",\"contentUrl\":\"https:\\\/\\\/www.scalemonkey.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/ScaleMonkey-mail.jpg\",\"width\":591,\"height\":591,\"caption\":\"ScaleMonkey\"},\"image\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-ch\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/scalemonkey\\\/\",\"https:\\\/\\\/www.instagram.com\\\/scalemonkey\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@scalemonkeyofficial\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Travail du m\u00e9tal-Archiv | scalemonkey.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.scalemonkey.com\/fr-ch\/store\/garage-tools\/metalworking\/","og_locale":"fr_FR","og_type":"article","og_title":"Travail du m\u00e9tal-Archiv | scalemonkey.com","og_description":"Travail du m\u00e9talLe contr\u00f4le sur chaque dixi\u00e8me Le m\u00e9tal exige de bons outils et un travail contr\u00f4l\u00e9. Une coupe, une ar\u00eate ou un dixi\u00e8me de mati\u00e8re en trop ne se r\u00e9cup\u00e8rent pas facilement. Chez ScaleMonkey, tu trouveras des outils pour le travail du m\u00e9tal en mod\u00e9lisme. Pour limer, poncer, ajuster et retoucher des profil\u00e9s, des t\u00f4les et des composants \u2013 partout o\u00f9 la pr\u00e9cision dimensionnelle et un bon r\u00e9sultat comptent. Particuli\u00e8rement pour les constructions individuelles, l&#8217;ajustement final se fait souvent directement sur l&#8217;\u00e9tabli. Les ar\u00eates sont cass\u00e9es, les contours ajust\u00e9s, les surfaces travaill\u00e9es et les composants affin\u00e9s jusqu&#8217;\u00e0 ce que technique et esth\u00e9tique se rejoignent. Ce n&#8217;est pas du gros travail du m\u00e9tal en format r\u00e9duit. C&#8217;est de l&#8217;artisanat sur de petites pi\u00e8ces. Un dixi\u00e8me peut faire la diff\u00e9rence.","og_url":"https:\/\/www.scalemonkey.com\/fr-ch\/store\/garage-tools\/metalworking\/","og_site_name":"scalemonkey.com","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.scalemonkey.com\/fr-ch\/store\/garage-tools\/metalworking\/","url":"https:\/\/www.scalemonkey.com\/fr-ch\/store\/garage-tools\/metalworking\/","name":"Travail du m\u00e9tal-Archiv | scalemonkey.com","isPartOf":{"@id":"https:\/\/www.scalemonkey.com\/fr-ch\/#website"},"breadcrumb":{"@id":"https:\/\/www.scalemonkey.com\/fr-ch\/store\/garage-tools\/metalworking\/#breadcrumb"},"inLanguage":"fr-CH"},{"@type":"BreadcrumbList","@id":"https:\/\/www.scalemonkey.com\/fr-ch\/store\/garage-tools\/metalworking\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Start","item":"https:\/\/www.scalemonkey.com\/fr-ch\/home\/"},{"@type":"ListItem","position":2,"name":"Travail du m\u00e9tal"}]},{"@type":"WebSite","@id":"https:\/\/www.scalemonkey.com\/fr-ch\/#website","url":"https:\/\/www.scalemonkey.com\/fr-ch\/","name":"ScaleMonkey","description":"Anspruchsvoller RC-Modellbau, eigene Baus\u00e4tze, Rolling-Chassis, Upgrades und Zubeh\u00f6r.","publisher":{"@id":"https:\/\/www.scalemonkey.com\/fr-ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.scalemonkey.com\/fr-ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CH"},{"@type":"Organization","@id":"https:\/\/www.scalemonkey.com\/fr-ch\/#organization","name":"ScaleMonkey","url":"https:\/\/www.scalemonkey.com\/fr-ch\/","logo":{"@type":"ImageObject","inLanguage":"fr-CH","@id":"https:\/\/www.scalemonkey.com\/fr-ch\/#\/schema\/logo\/image\/","url":"https:\/\/www.scalemonkey.com\/wp-content\/uploads\/2026\/08\/ScaleMonkey-mail.jpg","contentUrl":"https:\/\/www.scalemonkey.com\/wp-content\/uploads\/2026\/08\/ScaleMonkey-mail.jpg","width":591,"height":591,"caption":"ScaleMonkey"},"image":{"@id":"https:\/\/www.scalemonkey.com\/fr-ch\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/scalemonkey\/","https:\/\/www.instagram.com\/scalemonkey\/","https:\/\/www.youtube.com\/@scalemonkeyofficial\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.scalemonkey.com\/fr-ch\/wp-json\/wp\/v2\/product_cat\/7024","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.scalemonkey.com\/fr-ch\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.scalemonkey.com\/fr-ch\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/www.scalemonkey.com\/fr-ch\/wp-json\/wp\/v2\/product_cat\/7013"}],"wp:post_type":[{"href":"https:\/\/www.scalemonkey.com\/fr-ch\/wp-json\/wp\/v2\/product?product_cat=7024"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}