{"id":227,"count":2,"description":"<h2 class=\"smc-custom-heading\">Anlenkungen<span class=\"smc-newline-separator\">Pr\u00e4zision beginnt in der Mechanik<\/span><\/h2>\r\nEine pr\u00e4zise Steuerung ist nur so gut wie die Mechanik, die ihre Bewegung \u00fcbertr\u00e4gt. Spiel, ung\u00fcnstige Geometrien oder schwerg\u00e4ngige Verbindungen machen selbst hochwertige Servotechnik zur Nebensache.\r\n\r\nBei ScaleMonkey findest du ausgew\u00e4hlte Komponenten f\u00fcr pr\u00e4zise und zuverl\u00e4ssige Anlenkungen im RC-Modellbau. Von Gest\u00e4ngen und Kugelk\u00f6pfen bis zu passenden Verbindungselementen \u2013 f\u00fcr Lenkungen, Schaltungen und mechanische Sonderfunktionen.\r\n\r\nEntscheidend ist das Zusammenspiel: Die Anlenkung muss zur Servokraft, zum ben\u00f6tigten Stellweg und zur jeweiligen Mechanik passen. Sauber ausgelegt, entsteht eine direkte und reproduzierbare Kraft\u00fcbertragung ohne unn\u00f6tiges Spiel.\r\n\r\n<strong>Was das Servo vorgibt, muss an der Mechanik ankommen.<\/strong>","link":"https:\/\/www.scalemonkey.com\/germany\/store\/model-building\/model-boats\/boat-parts\/linkages\/","name":"Anlenkungen","slug":"linkages","taxonomy":"product_cat","parent":223,"meta":[],"menu_order":29,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>RC-Anlenkungen &amp; Gest\u00e4nge f\u00fcr Modellbau | scalemonkey.com<\/title>\n<meta name=\"description\" content=\"RC-Anlenkungen f\u00fcr den Modellbau: Gest\u00e4nge, Kugelk\u00f6pfe und Verbindungselemente f\u00fcr direkte Lenkungen und mechanische Sonderfunktionen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.scalemonkey.com\/ro\/store\/model-building\/model-boats\/boat-parts\/linkages\/\" \/>\n<meta property=\"og:locale\" content=\"ro_RO\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"RC-Anlenkungen &amp; Gest\u00e4nge f\u00fcr Modellbau | scalemonkey.com\" \/>\n<meta property=\"og:description\" content=\"RC-Anlenkungen f\u00fcr den Modellbau: Gest\u00e4nge, Kugelk\u00f6pfe und Verbindungselemente f\u00fcr direkte Lenkungen und mechanische Sonderfunktionen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.scalemonkey.com\/germany\/store\/model-building\/model-boats\/boat-parts\/linkages\/\" \/>\n<meta property=\"og:site_name\" content=\"scalemonkey.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/germany\\\/store\\\/model-building\\\/model-boats\\\/boat-parts\\\/linkages\\\/\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/germany\\\/store\\\/model-building\\\/model-boats\\\/boat-parts\\\/linkages\\\/\",\"name\":\"RC-Anlenkungen & Gest\u00e4nge f\u00fcr Modellbau | scalemonkey.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/ro\\\/#website\"},\"description\":\"RC-Anlenkungen f\u00fcr den Modellbau: Gest\u00e4nge, Kugelk\u00f6pfe und Verbindungselemente f\u00fcr direkte Lenkungen und mechanische Sonderfunktionen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/germany\\\/store\\\/model-building\\\/model-boats\\\/boat-parts\\\/linkages\\\/#breadcrumb\"},\"inLanguage\":\"ro-RO\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/germany\\\/store\\\/model-building\\\/model-boats\\\/boat-parts\\\/linkages\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Start\",\"item\":\"https:\\\/\\\/www.scalemonkey.com\\\/ro\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Modelism &amp; Accesorii\",\"item\":\"https:\\\/\\\/www.scalemonkey.com\\\/ro\\\/store\\\/model-building\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Modelism naval\",\"item\":\"https:\\\/\\\/www.scalemonkey.com\\\/ro\\\/store\\\/model-building\\\/model-boats\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Accesorii Nave\",\"item\":\"https:\\\/\\\/www.scalemonkey.com\\\/ro\\\/store\\\/model-building\\\/model-boats\\\/boat-parts\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Tije de leg\u0103tur\u0103\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/ro\\\/#website\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/ro\\\/\",\"name\":\"ScaleMonkey\",\"description\":\"Anspruchsvoller RC-Modellbau, eigene Baus\u00e4tze, Rolling-Chassis, Upgrades und Zubeh\u00f6r.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/ro\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.scalemonkey.com\\\/ro\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ro-RO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/ro\\\/#organization\",\"name\":\"ScaleMonkey\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/ro\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ro-RO\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/ro\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/ScaleMonkey-mail.jpg\",\"contentUrl\":\"https:\\\/\\\/www.scalemonkey.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/ScaleMonkey-mail.jpg\",\"width\":591,\"height\":591,\"caption\":\"ScaleMonkey\"},\"image\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/ro\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/scalemonkey\\\/\",\"https:\\\/\\\/www.instagram.com\\\/scalemonkey\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@scalemonkeyofficial\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"RC-Anlenkungen & Gest\u00e4nge f\u00fcr Modellbau | scalemonkey.com","description":"RC-Anlenkungen f\u00fcr den Modellbau: Gest\u00e4nge, Kugelk\u00f6pfe und Verbindungselemente f\u00fcr direkte Lenkungen und mechanische Sonderfunktionen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.scalemonkey.com\/ro\/store\/model-building\/model-boats\/boat-parts\/linkages\/","og_locale":"ro_RO","og_type":"article","og_title":"RC-Anlenkungen & Gest\u00e4nge f\u00fcr Modellbau | scalemonkey.com","og_description":"RC-Anlenkungen f\u00fcr den Modellbau: Gest\u00e4nge, Kugelk\u00f6pfe und Verbindungselemente f\u00fcr direkte Lenkungen und mechanische Sonderfunktionen.","og_url":"https:\/\/www.scalemonkey.com\/germany\/store\/model-building\/model-boats\/boat-parts\/linkages\/","og_site_name":"scalemonkey.com","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.scalemonkey.com\/germany\/store\/model-building\/model-boats\/boat-parts\/linkages\/","url":"https:\/\/www.scalemonkey.com\/germany\/store\/model-building\/model-boats\/boat-parts\/linkages\/","name":"RC-Anlenkungen & Gest\u00e4nge f\u00fcr Modellbau | scalemonkey.com","isPartOf":{"@id":"https:\/\/www.scalemonkey.com\/ro\/#website"},"description":"RC-Anlenkungen f\u00fcr den Modellbau: Gest\u00e4nge, Kugelk\u00f6pfe und Verbindungselemente f\u00fcr direkte Lenkungen und mechanische Sonderfunktionen.","breadcrumb":{"@id":"https:\/\/www.scalemonkey.com\/germany\/store\/model-building\/model-boats\/boat-parts\/linkages\/#breadcrumb"},"inLanguage":"ro-RO"},{"@type":"BreadcrumbList","@id":"https:\/\/www.scalemonkey.com\/germany\/store\/model-building\/model-boats\/boat-parts\/linkages\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Start","item":"https:\/\/www.scalemonkey.com\/ro\/home\/"},{"@type":"ListItem","position":2,"name":"Modelism &amp; Accesorii","item":"https:\/\/www.scalemonkey.com\/ro\/store\/model-building\/"},{"@type":"ListItem","position":3,"name":"Modelism naval","item":"https:\/\/www.scalemonkey.com\/ro\/store\/model-building\/model-boats\/"},{"@type":"ListItem","position":4,"name":"Accesorii Nave","item":"https:\/\/www.scalemonkey.com\/ro\/store\/model-building\/model-boats\/boat-parts\/"},{"@type":"ListItem","position":5,"name":"Tije de leg\u0103tur\u0103"}]},{"@type":"WebSite","@id":"https:\/\/www.scalemonkey.com\/ro\/#website","url":"https:\/\/www.scalemonkey.com\/ro\/","name":"ScaleMonkey","description":"Anspruchsvoller RC-Modellbau, eigene Baus\u00e4tze, Rolling-Chassis, Upgrades und Zubeh\u00f6r.","publisher":{"@id":"https:\/\/www.scalemonkey.com\/ro\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.scalemonkey.com\/ro\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ro-RO"},{"@type":"Organization","@id":"https:\/\/www.scalemonkey.com\/ro\/#organization","name":"ScaleMonkey","url":"https:\/\/www.scalemonkey.com\/ro\/","logo":{"@type":"ImageObject","inLanguage":"ro-RO","@id":"https:\/\/www.scalemonkey.com\/ro\/#\/schema\/logo\/image\/","url":"https:\/\/www.scalemonkey.com\/wp-content\/uploads\/2026\/08\/ScaleMonkey-mail.jpg","contentUrl":"https:\/\/www.scalemonkey.com\/wp-content\/uploads\/2026\/08\/ScaleMonkey-mail.jpg","width":591,"height":591,"caption":"ScaleMonkey"},"image":{"@id":"https:\/\/www.scalemonkey.com\/ro\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/scalemonkey\/","https:\/\/www.instagram.com\/scalemonkey\/","https:\/\/www.youtube.com\/@scalemonkeyofficial\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.scalemonkey.com\/ro\/wp-json\/wp\/v2\/product_cat\/227","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.scalemonkey.com\/ro\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.scalemonkey.com\/ro\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/www.scalemonkey.com\/ro\/wp-json\/wp\/v2\/product_cat\/223"}],"wp:post_type":[{"href":"https:\/\/www.scalemonkey.com\/ro\/wp-json\/wp\/v2\/product?product_cat=227"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}