{"id":2067,"count":0,"description":"Thomas Flinn &amp; Co Ltd.\nDesde 1923 que a nossa fam\u00edlia fabrica serras e ferramentas manuais nas nossas f\u00e1bricas em Sheffield. Os nossos artes\u00e3os produzem uma vasta gama de serras sob marcas tradicionais famosas, cujas origens remontam ao s\u00e9culo XVIII. As nossas marcas populares s\u00e3o a marca PAX, Lynx Saws (Garlick Saw Company) e Roberts &amp; Lee Dorchester Saws. Tamb\u00e9m fabricamos plainas manuais Clifton, que incluem uma ampla gama de plainas de bancada, plainas de ombro e plainas de raiar de alta qualidade.   ","link":"https:\/\/www.scalemonkey.com\/pt\/brands\/thomas-flinn-co\/","name":"Thomas Flinn &amp; Co.","slug":"thomas-flinn-co","taxonomy":"berocket_brand","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Thomas Flinn &amp; Co. | ScaleMonkey<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.scalemonkey.com\/pt\/brands\/thomas-flinn-co\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Thomas Flinn &amp; Co. | ScaleMonkey\" \/>\n<meta property=\"og:description\" content=\"Thomas Flinn &amp; Co Ltd. Desde 1923 que a nossa fam\u00edlia fabrica serras e ferramentas manuais nas nossas f\u00e1bricas em Sheffield. Os nossos artes\u00e3os produzem uma vasta gama de serras sob marcas tradicionais famosas, cujas origens remontam ao s\u00e9culo XVIII. As nossas marcas populares s\u00e3o a marca PAX, Lynx Saws (Garlick Saw Company) e Roberts &amp; Lee Dorchester Saws. Tamb\u00e9m fabricamos plainas manuais Clifton, que incluem uma ampla gama de plainas de bancada, plainas de ombro e plainas de raiar de alta qualidade.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.scalemonkey.com\/pt\/brands\/thomas-flinn-co\/\" \/>\n<meta property=\"og:site_name\" content=\"ScaleMonkey\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/pt\\\/brands\\\/thomas-flinn-co\\\/\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/pt\\\/brands\\\/thomas-flinn-co\\\/\",\"name\":\"Thomas Flinn &amp; Co. | ScaleMonkey\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/pt\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/pt\\\/brands\\\/thomas-flinn-co\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/pt\\\/brands\\\/thomas-flinn-co\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.scalemonkey.com\\\/pt\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Thomas Flinn &amp; Co.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/pt\\\/\",\"name\":\"ScaleMonkey\",\"description\":\"RC-Modelle in Perfektion, Pr\u00e4zision, Leidenschaft, Innovation \u2013 das ist ScaleMonkey. Wir denken Modellbau weiter und schaffen RC-Modelle, die durch Leistung, Detailtreue und Qualit\u00e4t \u00fcberzeugen.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.scalemonkey.com\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/pt\\\/#organization\",\"name\":\"ScaleMonkey\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/ScaleMonkey-mail.jpg\",\"contentUrl\":\"https:\\\/\\\/www.scalemonkey.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/ScaleMonkey-mail.jpg\",\"width\":591,\"height\":591,\"caption\":\"ScaleMonkey\"},\"image\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/scalemonkeyofficial\\\/\",\"https:\\\/\\\/www.instagram.com\\\/scalemonkey\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@scalemonkeyofficial\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Thomas Flinn &amp; Co. | ScaleMonkey","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.scalemonkey.com\/pt\/brands\/thomas-flinn-co\/","og_locale":"pt_PT","og_type":"article","og_title":"Thomas Flinn &amp; Co. | ScaleMonkey","og_description":"Thomas Flinn &amp; Co Ltd. Desde 1923 que a nossa fam\u00edlia fabrica serras e ferramentas manuais nas nossas f\u00e1bricas em Sheffield. Os nossos artes\u00e3os produzem uma vasta gama de serras sob marcas tradicionais famosas, cujas origens remontam ao s\u00e9culo XVIII. As nossas marcas populares s\u00e3o a marca PAX, Lynx Saws (Garlick Saw Company) e Roberts &amp; Lee Dorchester Saws. Tamb\u00e9m fabricamos plainas manuais Clifton, que incluem uma ampla gama de plainas de bancada, plainas de ombro e plainas de raiar de alta qualidade.","og_url":"https:\/\/www.scalemonkey.com\/pt\/brands\/thomas-flinn-co\/","og_site_name":"ScaleMonkey","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.scalemonkey.com\/pt\/brands\/thomas-flinn-co\/","url":"https:\/\/www.scalemonkey.com\/pt\/brands\/thomas-flinn-co\/","name":"Thomas Flinn &amp; Co. | ScaleMonkey","isPartOf":{"@id":"https:\/\/www.scalemonkey.com\/pt\/#website"},"breadcrumb":{"@id":"https:\/\/www.scalemonkey.com\/pt\/brands\/thomas-flinn-co\/#breadcrumb"},"inLanguage":"pt-PT"},{"@type":"BreadcrumbList","@id":"https:\/\/www.scalemonkey.com\/pt\/brands\/thomas-flinn-co\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.scalemonkey.com\/pt\/home\/"},{"@type":"ListItem","position":2,"name":"Thomas Flinn &amp; Co."}]},{"@type":"WebSite","@id":"https:\/\/www.scalemonkey.com\/pt\/#website","url":"https:\/\/www.scalemonkey.com\/pt\/","name":"ScaleMonkey","description":"RC-Modelle in Perfektion, Pr\u00e4zision, Leidenschaft, Innovation \u2013 das ist ScaleMonkey. Wir denken Modellbau weiter und schaffen RC-Modelle, die durch Leistung, Detailtreue und Qualit\u00e4t \u00fcberzeugen.","publisher":{"@id":"https:\/\/www.scalemonkey.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.scalemonkey.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.scalemonkey.com\/pt\/#organization","name":"ScaleMonkey","url":"https:\/\/www.scalemonkey.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.scalemonkey.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.scalemonkey.com\/wp-content\/uploads\/2025\/11\/ScaleMonkey-mail.jpg","contentUrl":"https:\/\/www.scalemonkey.com\/wp-content\/uploads\/2025\/11\/ScaleMonkey-mail.jpg","width":591,"height":591,"caption":"ScaleMonkey"},"image":{"@id":"https:\/\/www.scalemonkey.com\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/scalemonkeyofficial\/","https:\/\/www.instagram.com\/scalemonkey\/","https:\/\/www.youtube.com\/@scalemonkeyofficial\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.scalemonkey.com\/pt\/wp-json\/wp\/v2\/berocket_brand\/2067","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.scalemonkey.com\/pt\/wp-json\/wp\/v2\/berocket_brand"}],"about":[{"href":"https:\/\/www.scalemonkey.com\/pt\/wp-json\/wp\/v2\/taxonomies\/berocket_brand"}],"wp:post_type":[{"href":"https:\/\/www.scalemonkey.com\/pt\/wp-json\/wp\/v2\/product?berocket_brand=2067"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}