{"id":6413,"count":2,"description":"<h2 class=\"smc-custom-heading\">Rinvii<span class=\"smc-newline-separator\">La precisione inizia nella meccanica<\/span><\/h2>\nUn controllo preciso \u00e8 valido solo quanto la meccanica che trasmette il suo movimento. Giochi, geometrie sfavorevoli o collegamenti duri rendono secondaria anche la tecnologia dei servi di alta qualit\u00e0. \n\nSu ScaleMonkey trovi componenti selezionati per rinvii precisi e affidabili nel modellismo RC. Dalle aste e teste a sfera fino agli elementi di collegamento adatti \u2013 per sterzi, cambi e funzioni meccaniche speciali. \n\nDecisiva \u00e8 l'interazione: il rinvio deve adattarsi alla forza del servo, alla corsa necessaria e alla rispettiva meccanica. Progettato correttamente, si ottiene una trasmissione della forza diretta e riproducibile senza giochi inutili. \n\n<strong>Ci\u00f2 che il servo imposta deve arrivare alla meccanica.<\/strong>","link":"https:\/\/www.scalemonkey.com\/it\/store\/model-building\/model-boats\/boat-parts\/linkages\/","name":"Rinvii","slug":"linkages","taxonomy":"product_cat","parent":6412,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rinvii-Archiv | scalemonkey.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.scalemonkey.com\/it\/store\/model-building\/model-boats\/boat-parts\/linkages\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rinvii-Archiv | scalemonkey.com\" \/>\n<meta property=\"og:description\" content=\"RinviiLa precisione inizia nella meccanica Un controllo preciso \u00e8 valido solo quanto la meccanica che trasmette il suo movimento. Giochi, geometrie sfavorevoli o collegamenti duri rendono secondaria anche la tecnologia dei servi di alta qualit\u00e0. Su ScaleMonkey trovi componenti selezionati per rinvii precisi e affidabili nel modellismo RC. Dalle aste e teste a sfera fino agli elementi di collegamento adatti \u2013 per sterzi, cambi e funzioni meccaniche speciali. Decisiva \u00e8 l&#8217;interazione: il rinvio deve adattarsi alla forza del servo, alla corsa necessaria e alla rispettiva meccanica. Progettato correttamente, si ottiene una trasmissione della forza diretta e riproducibile senza giochi inutili. Ci\u00f2 che il servo imposta deve arrivare alla meccanica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.scalemonkey.com\/it\/store\/model-building\/model-boats\/boat-parts\/linkages\/\" \/>\n<meta property=\"og:site_name\" content=\"scalemonkey.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/it\\\/store\\\/model-building\\\/model-boats\\\/boat-parts\\\/linkages\\\/\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/it\\\/store\\\/model-building\\\/model-boats\\\/boat-parts\\\/linkages\\\/\",\"name\":\"Rinvii-Archiv | scalemonkey.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/it\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/it\\\/store\\\/model-building\\\/model-boats\\\/boat-parts\\\/linkages\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/it\\\/store\\\/model-building\\\/model-boats\\\/boat-parts\\\/linkages\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Start\",\"item\":\"https:\\\/\\\/www.scalemonkey.com\\\/it\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rinvii\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/it\\\/\",\"name\":\"ScaleMonkey\",\"description\":\"Anspruchsvoller RC-Modellbau, eigene Baus\u00e4tze, Rolling-Chassis, Upgrades und Zubeh\u00f6r.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.scalemonkey.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/it\\\/#organization\",\"name\":\"ScaleMonkey\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/ScaleMonkey-mail.jpg\",\"contentUrl\":\"https:\\\/\\\/www.scalemonkey.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/ScaleMonkey-mail.jpg\",\"width\":591,\"height\":591,\"caption\":\"ScaleMonkey\"},\"image\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/scalemonkey\\\/\",\"https:\\\/\\\/www.instagram.com\\\/scalemonkey\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@scalemonkeyofficial\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rinvii-Archiv | scalemonkey.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.scalemonkey.com\/it\/store\/model-building\/model-boats\/boat-parts\/linkages\/","og_locale":"it_IT","og_type":"article","og_title":"Rinvii-Archiv | scalemonkey.com","og_description":"RinviiLa precisione inizia nella meccanica Un controllo preciso \u00e8 valido solo quanto la meccanica che trasmette il suo movimento. Giochi, geometrie sfavorevoli o collegamenti duri rendono secondaria anche la tecnologia dei servi di alta qualit\u00e0. Su ScaleMonkey trovi componenti selezionati per rinvii precisi e affidabili nel modellismo RC. Dalle aste e teste a sfera fino agli elementi di collegamento adatti \u2013 per sterzi, cambi e funzioni meccaniche speciali. Decisiva \u00e8 l&#8217;interazione: il rinvio deve adattarsi alla forza del servo, alla corsa necessaria e alla rispettiva meccanica. Progettato correttamente, si ottiene una trasmissione della forza diretta e riproducibile senza giochi inutili. Ci\u00f2 che il servo imposta deve arrivare alla meccanica.","og_url":"https:\/\/www.scalemonkey.com\/it\/store\/model-building\/model-boats\/boat-parts\/linkages\/","og_site_name":"scalemonkey.com","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.scalemonkey.com\/it\/store\/model-building\/model-boats\/boat-parts\/linkages\/","url":"https:\/\/www.scalemonkey.com\/it\/store\/model-building\/model-boats\/boat-parts\/linkages\/","name":"Rinvii-Archiv | scalemonkey.com","isPartOf":{"@id":"https:\/\/www.scalemonkey.com\/it\/#website"},"breadcrumb":{"@id":"https:\/\/www.scalemonkey.com\/it\/store\/model-building\/model-boats\/boat-parts\/linkages\/#breadcrumb"},"inLanguage":"it-IT"},{"@type":"BreadcrumbList","@id":"https:\/\/www.scalemonkey.com\/it\/store\/model-building\/model-boats\/boat-parts\/linkages\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Start","item":"https:\/\/www.scalemonkey.com\/it\/home\/"},{"@type":"ListItem","position":2,"name":"Rinvii"}]},{"@type":"WebSite","@id":"https:\/\/www.scalemonkey.com\/it\/#website","url":"https:\/\/www.scalemonkey.com\/it\/","name":"ScaleMonkey","description":"Anspruchsvoller RC-Modellbau, eigene Baus\u00e4tze, Rolling-Chassis, Upgrades und Zubeh\u00f6r.","publisher":{"@id":"https:\/\/www.scalemonkey.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.scalemonkey.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.scalemonkey.com\/it\/#organization","name":"ScaleMonkey","url":"https:\/\/www.scalemonkey.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.scalemonkey.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.scalemonkey.com\/wp-content\/uploads\/2026\/08\/ScaleMonkey-mail.jpg","contentUrl":"https:\/\/www.scalemonkey.com\/wp-content\/uploads\/2026\/08\/ScaleMonkey-mail.jpg","width":591,"height":591,"caption":"ScaleMonkey"},"image":{"@id":"https:\/\/www.scalemonkey.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/scalemonkey\/","https:\/\/www.instagram.com\/scalemonkey\/","https:\/\/www.youtube.com\/@scalemonkeyofficial\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.scalemonkey.com\/it\/wp-json\/wp\/v2\/product_cat\/6413","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.scalemonkey.com\/it\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.scalemonkey.com\/it\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/www.scalemonkey.com\/it\/wp-json\/wp\/v2\/product_cat\/6412"}],"wp:post_type":[{"href":"https:\/\/www.scalemonkey.com\/it\/wp-json\/wp\/v2\/product?product_cat=6413"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}