{"id":36308,"date":"2025-07-20T10:28:33","date_gmt":"2025-07-20T08:28:33","guid":{"rendered":"https:\/\/www.scalemonkey.com\/p\/generatore-dc-per-motore-cison-v8-ohv\/"},"modified":"2026-07-10T12:58:36","modified_gmt":"2026-07-10T10:58:36","slug":"dc-generator-for-cison-v8-ohv-engine","status":"publish","type":"product","link":"https:\/\/www.scalemonkey.com\/it\/p\/dc-generator-for-cison-v8-ohv-engine\/","title":{"rendered":"<div class=\"bapl_ajax_replace bapl_ajax_tleft\" style=\"display:none;\" data-id=\"36308\"><\/div>Generatore DC per motore Cison V8 OHV<div class=\"bapl_ajax_replace bapl_ajax_tright\" style=\"display:none;\" data-id=\"36308\"><\/div>"},"content":{"rendered":"<p>Generatore DC in miniatura per il motore Cison V8. Il generatore ha un design estremamente realistico e riproduce fedelmente ogni dettaglio. Grazie al suo aspetto raffinato e compatto, aggiunge valore estetico e dettagli di pregio al tuo modello di motore. Se azionato da una macchina a vapore o da un motore a combustione, genera una tensione di 12 V con una corrente di circa 1 A; se invece viene applicata una tensione continua di 12 V ai morsetti, funziona come motore. \u00c8 perfettamente adattato ai modelli di motori della serie CISON. Si fissa con una staffa ed \u00e8 collegato all&#8217;albero principale tramite una cinghia. Pu\u00f2 alimentare l&#8217;accensione CDI senza alimentazione esterna, eliminando la necessit\u00e0 di un collegamento diretto alla rete elettrica.      <\/p>\n<pre>Dati:<\/pre>\n<ul>\n<li>Metodo di collegamento al mandrino: collegamento a cinghia<\/li>\n<li>Tensione di generazione: 12 V<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Generatore DC in miniatura per il motore Cison V8. Il generatore ha un design estremamente realistico e riproduce fedelmente ogni dettaglio. Grazie al suo aspetto raffinato e compatto, aggiunge valore [&hellip;]<\/p>\n","protected":false},"featured_media":36309,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_glsr_average":0,"_glsr_ranking":0,"_glsr_reviews":0},"product_cat":[747],"product_tag":[436],"berocket_brand":[746],"class_list":["post-36308","product","type-product","status-publish","has-post-thumbnail","product_cat-engine-accessories","product_tag-v8-engines","product_shipping_class-standard-shipping","berocket_brand-cison-engine","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Generatore DC per motore Cison V8 OHV | ScaleMonkey<\/title>\n<meta name=\"description\" content=\"Generatore DC per motore Cison V8\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.scalemonkey.com\/it\/p\/dc-generator-for-cison-v8-ohv-engine\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Generatore DC per motore Cison V8 OHV | ScaleMonkey\" \/>\n<meta property=\"og:description\" content=\"Generatore DC per motore Cison V8\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.scalemonkey.com\/it\/p\/dc-generator-for-cison-v8-ohv-engine\/\" \/>\n<meta property=\"og:site_name\" content=\"ScaleMonkey\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/scalemonkeyofficial\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-10T10:58:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.scalemonkey.com\/wp-content\/uploads\/2025\/11\/micro-electric-dc-generator.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/it\\\/p\\\/dc-generator-for-cison-v8-ohv-engine\\\/\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/it\\\/p\\\/dc-generator-for-cison-v8-ohv-engine\\\/\",\"name\":\"Generatore DC per motore Cison V8 OHV | ScaleMonkey\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/it\\\/p\\\/dc-generator-for-cison-v8-ohv-engine\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/it\\\/p\\\/dc-generator-for-cison-v8-ohv-engine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.scalemonkey.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/micro-electric-dc-generator.jpg\",\"datePublished\":\"2025-07-20T08:28:33+00:00\",\"dateModified\":\"2026-07-10T10:58:36+00:00\",\"description\":\"Generatore DC per motore Cison V8\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/it\\\/p\\\/dc-generator-for-cison-v8-ohv-engine\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.scalemonkey.com\\\/it\\\/p\\\/dc-generator-for-cison-v8-ohv-engine\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/it\\\/p\\\/dc-generator-for-cison-v8-ohv-engine\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/micro-electric-dc-generator.jpg\",\"contentUrl\":\"https:\\\/\\\/www.scalemonkey.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/micro-electric-dc-generator.jpg\",\"width\":1000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/it\\\/p\\\/dc-generator-for-cison-v8-ohv-engine\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.scalemonkey.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Negozio\",\"item\":\"https:\\\/\\\/www.scalemonkey.com\\\/it\\\/store\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Generatore DC per motore Cison V8 OHV\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/it\\\/\",\"name\":\"ScaleMonkey\",\"description\":\"RC-Modelle in Perfektion, Pr\u00e4zision, Leidenschaft, Innovation \u2013 das ist ScaleMonkey. Wir denken Modellbau weiter und schaffen RC-Modelle, die durch Leistung, Detailtreue und Qualit\u00e4t \u00fcberzeugen.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.scalemonkey.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/it\\\/#organization\",\"name\":\"ScaleMonkey\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/ScaleMonkey-mail.jpg\",\"contentUrl\":\"https:\\\/\\\/www.scalemonkey.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/ScaleMonkey-mail.jpg\",\"width\":591,\"height\":591,\"caption\":\"ScaleMonkey\"},\"image\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/scalemonkeyofficial\\\/\",\"https:\\\/\\\/www.instagram.com\\\/scalemonkey\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@scalemonkeyofficial\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Generatore DC per motore Cison V8 OHV | ScaleMonkey","description":"Generatore DC per motore Cison V8","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.scalemonkey.com\/it\/p\/dc-generator-for-cison-v8-ohv-engine\/","og_locale":"it_IT","og_type":"article","og_title":"Generatore DC per motore Cison V8 OHV | ScaleMonkey","og_description":"Generatore DC per motore Cison V8","og_url":"https:\/\/www.scalemonkey.com\/it\/p\/dc-generator-for-cison-v8-ohv-engine\/","og_site_name":"ScaleMonkey","article_publisher":"https:\/\/www.facebook.com\/scalemonkeyofficial\/","article_modified_time":"2026-07-10T10:58:36+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/www.scalemonkey.com\/wp-content\/uploads\/2025\/11\/micro-electric-dc-generator.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.scalemonkey.com\/it\/p\/dc-generator-for-cison-v8-ohv-engine\/","url":"https:\/\/www.scalemonkey.com\/it\/p\/dc-generator-for-cison-v8-ohv-engine\/","name":"Generatore DC per motore Cison V8 OHV | ScaleMonkey","isPartOf":{"@id":"https:\/\/www.scalemonkey.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.scalemonkey.com\/it\/p\/dc-generator-for-cison-v8-ohv-engine\/#primaryimage"},"image":{"@id":"https:\/\/www.scalemonkey.com\/it\/p\/dc-generator-for-cison-v8-ohv-engine\/#primaryimage"},"thumbnailUrl":"https:\/\/www.scalemonkey.com\/wp-content\/uploads\/2025\/11\/micro-electric-dc-generator.jpg","datePublished":"2025-07-20T08:28:33+00:00","dateModified":"2026-07-10T10:58:36+00:00","description":"Generatore DC per motore Cison V8","breadcrumb":{"@id":"https:\/\/www.scalemonkey.com\/it\/p\/dc-generator-for-cison-v8-ohv-engine\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.scalemonkey.com\/it\/p\/dc-generator-for-cison-v8-ohv-engine\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.scalemonkey.com\/it\/p\/dc-generator-for-cison-v8-ohv-engine\/#primaryimage","url":"https:\/\/www.scalemonkey.com\/wp-content\/uploads\/2025\/11\/micro-electric-dc-generator.jpg","contentUrl":"https:\/\/www.scalemonkey.com\/wp-content\/uploads\/2025\/11\/micro-electric-dc-generator.jpg","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/www.scalemonkey.com\/it\/p\/dc-generator-for-cison-v8-ohv-engine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.scalemonkey.com\/it\/"},{"@type":"ListItem","position":2,"name":"Negozio","item":"https:\/\/www.scalemonkey.com\/it\/store\/"},{"@type":"ListItem","position":3,"name":"Generatore DC per motore Cison V8 OHV"}]},{"@type":"WebSite","@id":"https:\/\/www.scalemonkey.com\/it\/#website","url":"https:\/\/www.scalemonkey.com\/it\/","name":"ScaleMonkey","description":"RC-Modelle in Perfektion, Pr\u00e4zision, Leidenschaft, Innovation \u2013 das ist ScaleMonkey. Wir denken Modellbau weiter und schaffen RC-Modelle, die durch Leistung, Detailtreue und Qualit\u00e4t \u00fcberzeugen.","publisher":{"@id":"https:\/\/www.scalemonkey.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.scalemonkey.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.scalemonkey.com\/it\/#organization","name":"ScaleMonkey","url":"https:\/\/www.scalemonkey.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.scalemonkey.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.scalemonkey.com\/wp-content\/uploads\/2025\/11\/ScaleMonkey-mail.jpg","contentUrl":"https:\/\/www.scalemonkey.com\/wp-content\/uploads\/2025\/11\/ScaleMonkey-mail.jpg","width":591,"height":591,"caption":"ScaleMonkey"},"image":{"@id":"https:\/\/www.scalemonkey.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/scalemonkeyofficial\/","https:\/\/www.instagram.com\/scalemonkey\/","https:\/\/www.youtube.com\/@scalemonkeyofficial\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.scalemonkey.com\/it\/wp-json\/wp\/v2\/product\/36308","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.scalemonkey.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.scalemonkey.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.scalemonkey.com\/it\/wp-json\/wp\/v2\/comments?post=36308"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.scalemonkey.com\/it\/wp-json\/wp\/v2\/media\/36309"}],"wp:attachment":[{"href":"https:\/\/www.scalemonkey.com\/it\/wp-json\/wp\/v2\/media?parent=36308"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.scalemonkey.com\/it\/wp-json\/wp\/v2\/product_cat?post=36308"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.scalemonkey.com\/it\/wp-json\/wp\/v2\/product_tag?post=36308"},{"taxonomy":"berocket_brand","embeddable":true,"href":"https:\/\/www.scalemonkey.com\/it\/wp-json\/wp\/v2\/berocket_brand?post=36308"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}