{"id":35764,"date":"2025-07-30T10:28:11","date_gmt":"2025-07-30T08:28:11","guid":{"rendered":"https:\/\/www.scalemonkey.com\/p\/kst-ms3509-servo-32kg-cm7-4v\/"},"modified":"2026-07-10T12:58:08","modified_gmt":"2026-07-10T10:58:08","slug":"kst-ms3509-servo-32kg-cm7-4v","status":"publish","type":"product","link":"https:\/\/www.scalemonkey.com\/it\/p\/kst-ms3509-servo-32kg-cm7-4v\/","title":{"rendered":"<div class=\"bapl_ajax_replace bapl_ajax_tleft\" style=\"display:none;\" data-id=\"35764\"><\/div>KST MS3509 Servo 32kg.cm@7.4V<div class=\"bapl_ajax_replace bapl_ajax_tright\" style=\"display:none;\" data-id=\"35764\"><\/div>"},"content":{"rendered":"<p>KST DS3509MG<\/p>\n<h5>Dettagli tecnici:<\/h5>\n<ul>\n<li>Tensione di esercizio (max.) [V]:8.4<\/li>\n<\/ul>\n<ul>\n<li>Coppia di stallo [kg.cm]@6.0V:28.0<br \/>\nCoppia di stallo [kg.cm]@7.4V:32.0<\/li>\n<\/ul>\n<ul>\n<li>Tempo di posizionamento [s\/60\u00b0]@6.0V:0.150<br \/>\nTempo di posizionamento [s\/60\u00b0]@7.4V:0.140<\/li>\n<\/ul>\n<ul>\n<li>Range di posizionamento: \u00b1100\u00b0 a 500-2500us \/ \u00b150\u00b0 a 1000-2000us<\/li>\n<li>Larghezza [mm]: 21.0mm<\/li>\n<li>Lunghezza [mm]: 40.5mm<\/li>\n<li>Altezza [mm]: 38.5mm<\/li>\n<li>Peso [g]: 78.0mm<\/li>\n<li>Tipo di motore: Coreless<\/li>\n<li>Tipo di ingranaggi: Metallo<\/li>\n<li>Tipo di cuscinetti: 2BB<\/li>\n<li>Tipo di servo: Standard<\/li>\n<li>Elettronica: Digitale<\/li>\n<li>Sensore di posizione: Senza contatto<\/li>\n<li>Impermeabile: No<\/li>\n<li>Produttore: KST<\/li>\n<\/ul>\n<p>Ti preghiamo di considerare le specifiche del servo del produttore del modello nella scelta dei servo.<\/p>\n<div class=\"smc-link-underline\"><strong class=\"smc-description-note\">Download:<\/strong><br \/>\n<a href=\"https:\/\/www.scalemonkey.com\/wp-content\/uploads\/2024\/04\/MS3509_Specification.pdf\">MS3509_Specification<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>KST DS3509MG Dettagli tecnici: Tensione di esercizio (max.) [V]:8.4 Coppia di stallo [kg.cm]@6.0V:28.0 Coppia di stallo [kg.cm]@7.4V:32.0 Tempo di posizionamento [s\/60\u00b0]@6.0V:0.150 Tempo di posizionamento [s\/60\u00b0]@7.4V:0.140 Range di posizionamento: \u00b1100\u00b0 a [&hellip;]<\/p>\n","protected":false},"featured_media":35773,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_glsr_average":0,"_glsr_ranking":0,"_glsr_reviews":0},"product_cat":[623],"product_tag":[],"berocket_brand":[619],"class_list":["post-35764","product","type-product","status-publish","has-post-thumbnail","product_cat-21-25mm-servos","product_shipping_class-standard-shipping","berocket_brand-servo-digitale-kst","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>KST MS3509 Servo 32kg.cm@7.4V | ScaleMonkey<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.scalemonkey.com\/it\/p\/kst-ms3509-servo-32kg-cm7-4v\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"KST MS3509 Servo 32kg.cm@7.4V | ScaleMonkey\" \/>\n<meta property=\"og:description\" content=\"KST DS3509MG Dettagli tecnici: Tensione di esercizio (max.) [V]:8.4 Coppia di stallo [kg.cm]@6.0V:28.0 Coppia di stallo [kg.cm]@7.4V:32.0 Tempo di posizionamento [s\/60\u00b0]@6.0V:0.150 Tempo di posizionamento [s\/60\u00b0]@7.4V:0.140 Range di posizionamento: \u00b1100\u00b0 a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.scalemonkey.com\/it\/p\/kst-ms3509-servo-32kg-cm7-4v\/\" \/>\n<meta property=\"og:site_name\" content=\"ScaleMonkey\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/scalemonkeyofficial\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-10T10:58:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.scalemonkey.com\/wp-content\/uploads\/2025\/11\/KST-MS3509-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/it\\\/p\\\/kst-ms3509-servo-32kg-cm7-4v\\\/\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/it\\\/p\\\/kst-ms3509-servo-32kg-cm7-4v\\\/\",\"name\":\"KST MS3509 Servo 32kg.cm@7.4V | ScaleMonkey\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/it\\\/p\\\/kst-ms3509-servo-32kg-cm7-4v\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/it\\\/p\\\/kst-ms3509-servo-32kg-cm7-4v\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.scalemonkey.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/KST-MS3509-1.jpg\",\"datePublished\":\"2025-07-30T08:28:11+00:00\",\"dateModified\":\"2026-07-10T10:58:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/it\\\/p\\\/kst-ms3509-servo-32kg-cm7-4v\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.scalemonkey.com\\\/it\\\/p\\\/kst-ms3509-servo-32kg-cm7-4v\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/it\\\/p\\\/kst-ms3509-servo-32kg-cm7-4v\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/KST-MS3509-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.scalemonkey.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/KST-MS3509-1.jpg\",\"width\":1000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/it\\\/p\\\/kst-ms3509-servo-32kg-cm7-4v\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.scalemonkey.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Negozio\",\"item\":\"https:\\\/\\\/www.scalemonkey.com\\\/it\\\/store\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"KST MS3509 Servo 32kg.cm@7.4V\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/it\\\/\",\"name\":\"ScaleMonkey\",\"description\":\"RC-Modelle in Perfektion, Pr\u00e4zision, Leidenschaft, Innovation \u2013 das ist ScaleMonkey. Wir denken Modellbau weiter und schaffen RC-Modelle, die durch Leistung, Detailtreue und Qualit\u00e4t \u00fcberzeugen.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.scalemonkey.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/it\\\/#organization\",\"name\":\"ScaleMonkey\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/ScaleMonkey-mail.jpg\",\"contentUrl\":\"https:\\\/\\\/www.scalemonkey.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/ScaleMonkey-mail.jpg\",\"width\":591,\"height\":591,\"caption\":\"ScaleMonkey\"},\"image\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/scalemonkeyofficial\\\/\",\"https:\\\/\\\/www.instagram.com\\\/scalemonkey\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@scalemonkeyofficial\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"KST MS3509 Servo 32kg.cm@7.4V | ScaleMonkey","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.scalemonkey.com\/it\/p\/kst-ms3509-servo-32kg-cm7-4v\/","og_locale":"it_IT","og_type":"article","og_title":"KST MS3509 Servo 32kg.cm@7.4V | ScaleMonkey","og_description":"KST DS3509MG Dettagli tecnici: Tensione di esercizio (max.) [V]:8.4 Coppia di stallo [kg.cm]@6.0V:28.0 Coppia di stallo [kg.cm]@7.4V:32.0 Tempo di posizionamento [s\/60\u00b0]@6.0V:0.150 Tempo di posizionamento [s\/60\u00b0]@7.4V:0.140 Range di posizionamento: \u00b1100\u00b0 a [&hellip;]","og_url":"https:\/\/www.scalemonkey.com\/it\/p\/kst-ms3509-servo-32kg-cm7-4v\/","og_site_name":"ScaleMonkey","article_publisher":"https:\/\/www.facebook.com\/scalemonkeyofficial\/","article_modified_time":"2026-07-10T10:58:08+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/www.scalemonkey.com\/wp-content\/uploads\/2025\/11\/KST-MS3509-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.scalemonkey.com\/it\/p\/kst-ms3509-servo-32kg-cm7-4v\/","url":"https:\/\/www.scalemonkey.com\/it\/p\/kst-ms3509-servo-32kg-cm7-4v\/","name":"KST MS3509 Servo 32kg.cm@7.4V | ScaleMonkey","isPartOf":{"@id":"https:\/\/www.scalemonkey.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.scalemonkey.com\/it\/p\/kst-ms3509-servo-32kg-cm7-4v\/#primaryimage"},"image":{"@id":"https:\/\/www.scalemonkey.com\/it\/p\/kst-ms3509-servo-32kg-cm7-4v\/#primaryimage"},"thumbnailUrl":"https:\/\/www.scalemonkey.com\/wp-content\/uploads\/2025\/11\/KST-MS3509-1.jpg","datePublished":"2025-07-30T08:28:11+00:00","dateModified":"2026-07-10T10:58:08+00:00","breadcrumb":{"@id":"https:\/\/www.scalemonkey.com\/it\/p\/kst-ms3509-servo-32kg-cm7-4v\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.scalemonkey.com\/it\/p\/kst-ms3509-servo-32kg-cm7-4v\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.scalemonkey.com\/it\/p\/kst-ms3509-servo-32kg-cm7-4v\/#primaryimage","url":"https:\/\/www.scalemonkey.com\/wp-content\/uploads\/2025\/11\/KST-MS3509-1.jpg","contentUrl":"https:\/\/www.scalemonkey.com\/wp-content\/uploads\/2025\/11\/KST-MS3509-1.jpg","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/www.scalemonkey.com\/it\/p\/kst-ms3509-servo-32kg-cm7-4v\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.scalemonkey.com\/it\/"},{"@type":"ListItem","position":2,"name":"Negozio","item":"https:\/\/www.scalemonkey.com\/it\/store\/"},{"@type":"ListItem","position":3,"name":"KST MS3509 Servo 32kg.cm@7.4V"}]},{"@type":"WebSite","@id":"https:\/\/www.scalemonkey.com\/it\/#website","url":"https:\/\/www.scalemonkey.com\/it\/","name":"ScaleMonkey","description":"RC-Modelle in Perfektion, Pr\u00e4zision, Leidenschaft, Innovation \u2013 das ist ScaleMonkey. Wir denken Modellbau weiter und schaffen RC-Modelle, die durch Leistung, Detailtreue und Qualit\u00e4t \u00fcberzeugen.","publisher":{"@id":"https:\/\/www.scalemonkey.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.scalemonkey.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.scalemonkey.com\/it\/#organization","name":"ScaleMonkey","url":"https:\/\/www.scalemonkey.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.scalemonkey.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.scalemonkey.com\/wp-content\/uploads\/2025\/11\/ScaleMonkey-mail.jpg","contentUrl":"https:\/\/www.scalemonkey.com\/wp-content\/uploads\/2025\/11\/ScaleMonkey-mail.jpg","width":591,"height":591,"caption":"ScaleMonkey"},"image":{"@id":"https:\/\/www.scalemonkey.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/scalemonkeyofficial\/","https:\/\/www.instagram.com\/scalemonkey\/","https:\/\/www.youtube.com\/@scalemonkeyofficial\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.scalemonkey.com\/it\/wp-json\/wp\/v2\/product\/35764","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.scalemonkey.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.scalemonkey.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.scalemonkey.com\/it\/wp-json\/wp\/v2\/comments?post=35764"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.scalemonkey.com\/it\/wp-json\/wp\/v2\/media\/35773"}],"wp:attachment":[{"href":"https:\/\/www.scalemonkey.com\/it\/wp-json\/wp\/v2\/media?parent=35764"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.scalemonkey.com\/it\/wp-json\/wp\/v2\/product_cat?post=35764"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.scalemonkey.com\/it\/wp-json\/wp\/v2\/product_tag?post=35764"},{"taxonomy":"berocket_brand","embeddable":true,"href":"https:\/\/www.scalemonkey.com\/it\/wp-json\/wp\/v2\/berocket_brand?post=35764"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}