{"id":1023,"count":0,"description":"Special CollectionArticoli originali dal mondo del modellismo\n\nImmergiti nella nostra Special Collection \u2013 la categoria per chi nel modellismo vuole di pi\u00f9. Qui trovi articoli moderni, creativi e fuori dal comune che completano perfettamente la tua passione: abbigliamento stiloso e t-shirt a tema modellismo, gadget originali e pezzi da collezione speciali che si distinguono sicuramente. \n\nChe sia per la tua officina, la tua collezione o semplicemente per il tuo look, questa collezione porta design freschi, umorismo e veri elementi d'attrazione nel mondo del modellismo. Perfetta per chi ama l'individualit\u00e0 e vuole mostrare il proprio stile di vita hobbistico anche all'esterno. ","link":"https:\/\/www.scalemonkey.com\/it-ch\/store\/special-collection\/","name":"Special Collection","slug":"special-collection","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Special Collection-Archiv | ScaleMonkey<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.scalemonkey.com\/it-ch\/store\/special-collection\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Special Collection-Archiv | ScaleMonkey\" \/>\n<meta property=\"og:description\" content=\"Special CollectionArticoli originali dal mondo del modellismo Immergiti nella nostra Special Collection \u2013 la categoria per chi nel modellismo vuole di pi\u00f9. Qui trovi articoli moderni, creativi e fuori dal comune che completano perfettamente la tua passione: abbigliamento stiloso e t-shirt a tema modellismo, gadget originali e pezzi da collezione speciali che si distinguono sicuramente. Che sia per la tua officina, la tua collezione o semplicemente per il tuo look, questa collezione porta design freschi, umorismo e veri elementi d&#8217;attrazione nel mondo del modellismo. Perfetta per chi ama l&#8217;individualit\u00e0 e vuole mostrare il proprio stile di vita hobbistico anche all&#8217;esterno.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.scalemonkey.com\/it-ch\/store\/special-collection\/\" \/>\n<meta property=\"og:site_name\" content=\"ScaleMonkey\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/it-ch\\\/store\\\/special-collection\\\/\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/it-ch\\\/store\\\/special-collection\\\/\",\"name\":\"Special Collection-Archiv | ScaleMonkey\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/it-ch\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/it-ch\\\/store\\\/special-collection\\\/#breadcrumb\"},\"inLanguage\":\"it-CH\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/it-ch\\\/store\\\/special-collection\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.scalemonkey.com\\\/it-ch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Special Collection\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/it-ch\\\/#website\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/it-ch\\\/\",\"name\":\"ScaleMonkey\",\"description\":\"RC-Modelle in Perfektion, Pr\u00e4zision, Leidenschaft, Innovation \u2013 das ist ScaleMonkey. Wir denken Modellbau weiter und schaffen RC-Modelle, die durch Leistung, Detailtreue und Qualit\u00e4t \u00fcberzeugen.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/it-ch\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.scalemonkey.com\\\/it-ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-CH\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/it-ch\\\/#organization\",\"name\":\"ScaleMonkey\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/it-ch\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-CH\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/it-ch\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/ScaleMonkey-mail.jpg\",\"contentUrl\":\"https:\\\/\\\/www.scalemonkey.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/ScaleMonkey-mail.jpg\",\"width\":591,\"height\":591,\"caption\":\"ScaleMonkey\"},\"image\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/it-ch\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/scalemonkeyofficial\\\/\",\"https:\\\/\\\/www.instagram.com\\\/scalemonkey\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@scalemonkeyofficial\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Special Collection-Archiv | ScaleMonkey","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.scalemonkey.com\/it-ch\/store\/special-collection\/","og_locale":"it_IT","og_type":"article","og_title":"Special Collection-Archiv | ScaleMonkey","og_description":"Special CollectionArticoli originali dal mondo del modellismo Immergiti nella nostra Special Collection \u2013 la categoria per chi nel modellismo vuole di pi\u00f9. Qui trovi articoli moderni, creativi e fuori dal comune che completano perfettamente la tua passione: abbigliamento stiloso e t-shirt a tema modellismo, gadget originali e pezzi da collezione speciali che si distinguono sicuramente. Che sia per la tua officina, la tua collezione o semplicemente per il tuo look, questa collezione porta design freschi, umorismo e veri elementi d&#8217;attrazione nel mondo del modellismo. Perfetta per chi ama l&#8217;individualit\u00e0 e vuole mostrare il proprio stile di vita hobbistico anche all&#8217;esterno.","og_url":"https:\/\/www.scalemonkey.com\/it-ch\/store\/special-collection\/","og_site_name":"ScaleMonkey","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.scalemonkey.com\/it-ch\/store\/special-collection\/","url":"https:\/\/www.scalemonkey.com\/it-ch\/store\/special-collection\/","name":"Special Collection-Archiv | ScaleMonkey","isPartOf":{"@id":"https:\/\/www.scalemonkey.com\/it-ch\/#website"},"breadcrumb":{"@id":"https:\/\/www.scalemonkey.com\/it-ch\/store\/special-collection\/#breadcrumb"},"inLanguage":"it-CH"},{"@type":"BreadcrumbList","@id":"https:\/\/www.scalemonkey.com\/it-ch\/store\/special-collection\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.scalemonkey.com\/it-ch\/"},{"@type":"ListItem","position":2,"name":"Special Collection"}]},{"@type":"WebSite","@id":"https:\/\/www.scalemonkey.com\/it-ch\/#website","url":"https:\/\/www.scalemonkey.com\/it-ch\/","name":"ScaleMonkey","description":"RC-Modelle in Perfektion, Pr\u00e4zision, Leidenschaft, Innovation \u2013 das ist ScaleMonkey. Wir denken Modellbau weiter und schaffen RC-Modelle, die durch Leistung, Detailtreue und Qualit\u00e4t \u00fcberzeugen.","publisher":{"@id":"https:\/\/www.scalemonkey.com\/it-ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.scalemonkey.com\/it-ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-CH"},{"@type":"Organization","@id":"https:\/\/www.scalemonkey.com\/it-ch\/#organization","name":"ScaleMonkey","url":"https:\/\/www.scalemonkey.com\/it-ch\/","logo":{"@type":"ImageObject","inLanguage":"it-CH","@id":"https:\/\/www.scalemonkey.com\/it-ch\/#\/schema\/logo\/image\/","url":"https:\/\/www.scalemonkey.com\/wp-content\/uploads\/2025\/11\/ScaleMonkey-mail.jpg","contentUrl":"https:\/\/www.scalemonkey.com\/wp-content\/uploads\/2025\/11\/ScaleMonkey-mail.jpg","width":591,"height":591,"caption":"ScaleMonkey"},"image":{"@id":"https:\/\/www.scalemonkey.com\/it-ch\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/scalemonkeyofficial\/","https:\/\/www.instagram.com\/scalemonkey\/","https:\/\/www.youtube.com\/@scalemonkeyofficial\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.scalemonkey.com\/it-ch\/wp-json\/wp\/v2\/product_cat\/1023","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.scalemonkey.com\/it-ch\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.scalemonkey.com\/it-ch\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/www.scalemonkey.com\/it-ch\/wp-json\/wp\/v2\/product?product_cat=1023"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}