{"id":36337,"date":"2025-07-20T10:28:34","date_gmt":"2025-07-20T08:28:34","guid":{"rendered":"https:\/\/www.scalemonkey.com\/p\/moteur-rc-de-moto-bicylindre-en-v-cison-fg-vt9-9-cm%c2%b3\/"},"modified":"2026-07-10T12:59:06","modified_gmt":"2026-07-10T10:59:06","slug":"cison-fg-vt9-v-twin-motorcycle-rc-engine","status":"publish","type":"product","link":"https:\/\/www.scalemonkey.com\/fr\/p\/cison-fg-vt9-v-twin-motorcycle-rc-engine\/","title":{"rendered":"<div class=\"bapl_ajax_replace bapl_ajax_tleft\" style=\"display:none;\" data-id=\"36337\"><\/div>Moteur RC de moto bicylindre en V CISON FG-VT9 9 cm\u00b3<div class=\"bapl_ajax_replace bapl_ajax_tright\" style=\"display:none;\" data-id=\"36337\"><\/div>"},"content":{"rendered":"<p>Moteur \u00e0 essence RC de moto bicylindre en V V2 CISON FG-VT9 9 cm\u00b3 refroidi par air.<\/p>\n<p><em>Derni\u00e8re version !<\/em><\/p>\n<p><strong class=\"smc-description-note\">Principales am\u00e9liorations de la nouvelle version (FG-18VTP) :<\/strong><\/p>\n<ul>\n<li>Augmentation de la cylindr\u00e9e : Initialement de 9 cm\u00b3, puis port\u00e9e \u00e0 15,7 cm\u00b3 et maintenant \u00e0 18,2 cm\u00b3 pour plus de puissance et un fonctionnement plus souple.<\/li>\n<li>Al\u00e9sage plus grand : Augment\u00e9 de 16,67 mm \u00e0 20 mm pour une combustion am\u00e9lior\u00e9e.<\/li>\n<li>Course allong\u00e9e : Prolong\u00e9e de 21 mm \u00e0 29 mm pour un couple accru et une meilleure performance globale.<\/li>\n<li>Syst\u00e8me d&rsquo;\u00e9chappement am\u00e9lior\u00e9 : Le tuyau d&rsquo;\u00e9chappement en acier inoxydable pr\u00e9c\u00e9dent a \u00e9t\u00e9 remplac\u00e9 par un syst\u00e8me d&rsquo;\u00e9chappement imprim\u00e9 en 3D, plus l\u00e9ger et plus \u00e9l\u00e9gant.<\/li>\n<\/ul>\n<p>Un moteur V2, \u00e9galement appel\u00e9 V-twin, est un moteur bicylindre dont les cylindres forment un \u00ab V \u00bb. Il est \u00e9galement connu sous le nom de moteur Panhead, car il s&rsquo;agit d&rsquo;un moteur de moto suspendu de Harley-Davidson, ainsi nomm\u00e9 parce que les couvercles de culbuteurs rappellent des casseroles. Les moteurs sont dispos\u00e9s en V avec des angles sup\u00e9rieurs \u00e0 0, mais inf\u00e9rieurs \u00e0 180 degr\u00e9s. Parfois, les cylindres peuvent former un angle de 90 degr\u00e9s, ce qui est appel\u00e9 L-Twin. Ces moteurs sont principalement utilis\u00e9s pour leur taille compacte, leur rapport puissance\/cylindr\u00e9e \u00e9lev\u00e9 et leur faible rapport puissance\/couple. Depuis la fin des ann\u00e9es 1880, les moteurs V2 sont \u00e9galement utilis\u00e9s dans les motos et certaines petites voitures. Les moteurs V-twin les plus r\u00e9pandus sont les motos Harley Davidson \u00e0 45\u00b0, dont la plupart sont refroidies par air, mais il existe \u00e9galement des moteurs \u00e0 chemise d&rsquo;eau et le moteur VRod refroidi par eau. Les vibrations sont souvent associ\u00e9es au mythe du V-twin, mais elles sont un effet secondaire malheureux de la conception la plus populaire. Harley a plac\u00e9 les deux cylindres \u00e0 un angle de 45 degr\u00e9s l&rsquo;un par rapport \u00e0 l&rsquo;autre sur un carter commun afin que le moteur puisse s&rsquo;adapter \u00e0 un cadre de type v\u00e9lo, initialement pr\u00e9vu pour un moteur monocylindre. Malheureusement, un angle en V de 45 degr\u00e9s a une \u00ab signature vibratoire \u00bb distincte. La plupart des experts en moteurs s&rsquo;accordent \u00e0 dire que l&rsquo;\u00e2me du V-twin r\u00e9side dans la vibration et le tremblement du compartiment moteur. Il ne fait aucun doute que la plupart des connaisseurs de moteurs estiment que l&rsquo;\u00e2me du V-twin r\u00e9side dans le tremblement et le frisson du compartiment moteur.           <\/p>\n<pre>Contenu de la livraison :<\/pre>\n<ul>\n<li><strong>Moteur seul :<\/strong> Moteur enti\u00e8rement assembl\u00e9 avec syst\u00e8me d&rsquo;allumage et tuyaux d&rsquo;\u00e9chappement<\/li>\n<li><strong>Moteur avec socle en bois :<\/strong> Moteur enti\u00e8rement assembl\u00e9 sur socle en bois avec syst\u00e8me d&rsquo;allumage, tuyaux d&rsquo;\u00e9chappement, r\u00e9servoir et accessoires \u00e9lectroniques<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" title=\"Cison FG-VT9  9ccm V2 V-Twin RC Engine\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/8rnSE7nilbE?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p><strong>D\u00e9tails impressionnants :<\/strong><br \/>\nLe couvercle de culbuteur authentique sur la culasse classique et le couvercle de transmission permettent au mod\u00e8le de retrouver son charme d&rsquo;origine et de se rapprocher du moteur de moto r\u00e9el, en pr\u00e9sentant les caract\u00e9ristiques les plus remarquables d&rsquo;une moto d&rsquo;une certaine \u00e9poque.<\/p>\n<p><strong>Compatible avec les v\u00e9hicules RC :<\/strong><br \/>\nDispose d&rsquo;un diam\u00e8tre de cylindre plus grand et d&rsquo;une course plus longue pour une meilleure cylindr\u00e9e, ainsi que de bielles plus robustes pour offrir une excellente protection du couple lorsqu&rsquo;il est install\u00e9 sur les v\u00e9hicules.<\/p>\n<p><strong>Construction fiable :<\/strong><br \/>\nUtilise un m\u00e9canisme de soupapes OHV, un angle de 45\u00b0 entre deux cylindres, une chambre de combustion h\u00e9misph\u00e9rique r\u00e9aliste, un culbuteur d&rsquo;admission avec un angle en V, ainsi qu&rsquo;une chambre de couvercle de culbuteur amovible pour faciliter l&rsquo;observation et le r\u00e9glage du moteur.<\/p>\n<p><strong>Fiable et haute performance :<\/strong><br \/>\n\u00c9quip\u00e9 d&rsquo;un dissipateur thermique de grande surface pour des effets de refroidissement par air incroyables, le moteur est capable de fonctionner de mani\u00e8re stable en maintenant de faibles vitesses et prend en charge l&rsquo;utilisation de divers carburants pour une combustion plus uniforme gr\u00e2ce au carburateur optimis\u00e9.<\/p>\n<div class=\"smc-import-note\" style=\"text-align: center;\"><strong>Remarque sur le d\u00e9lai de livraison :<\/strong><br \/>\nCet article est import\u00e9 sur commande client. Des \u00e9carts mineurs peuvent donc survenir occasionnellement concernant le d\u00e9lai de livraison. Nous faisons de notre mieux pour respecter les d\u00e9lais de livraison indiqu\u00e9s et vous informerons bien entendu du statut actuel de votre commande.  <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Moteur \u00e0 essence RC de moto bicylindre en V V2 CISON FG-VT9 9 cm\u00b3 refroidi par air. Derni\u00e8re version ! Principales am\u00e9liorations de la nouvelle version (FG-18VTP) : Augmentation de [&hellip;]<\/p>\n","protected":false},"featured_media":36344,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_glsr_average":0,"_glsr_ranking":0,"_glsr_reviews":0},"product_cat":[762],"product_tag":[430],"berocket_brand":[749],"class_list":["post-36337","product","type-product","status-publish","has-post-thumbnail","product_cat-four-stroke-engine","product_tag-v2-engines","product_shipping_class-standard-shipping","berocket_brand-cison-engine","first","instock","taxable","shipping-taxable","purchasable","product-type-variable","wvs-archive-product-wrapper"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Moteur RC de moto bicylindre en V CISON FG-VT9 9 cm\u00b3 | ScaleMonkey<\/title>\n<meta name=\"description\" content=\"Moteur RC de moto bicylindre en V CISON FG-VT9 9 cm\u00b3\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.scalemonkey.com\/fr\/p\/cison-fg-vt9-v-twin-motorcycle-rc-engine\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Moteur RC de moto bicylindre en V CISON FG-VT9 9 cm\u00b3 | ScaleMonkey\" \/>\n<meta property=\"og:description\" content=\"Moteur RC de moto bicylindre en V CISON FG-VT9 9 cm\u00b3\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.scalemonkey.com\/fr\/p\/cison-fg-vt9-v-twin-motorcycle-rc-engine\/\" \/>\n<meta property=\"og:site_name\" content=\"ScaleMonkey\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/scalemonkeyofficial\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-10T10:59:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.scalemonkey.com\/wp-content\/uploads\/2025\/12\/CISON-FG-VT9-10.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1100\" \/>\n\t<meta property=\"og:image:height\" content=\"1100\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr\\\/p\\\/cison-fg-vt9-v-twin-motorcycle-rc-engine\\\/\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr\\\/p\\\/cison-fg-vt9-v-twin-motorcycle-rc-engine\\\/\",\"name\":\"Moteur RC de moto bicylindre en V CISON FG-VT9 9 cm\u00b3 | ScaleMonkey\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr\\\/p\\\/cison-fg-vt9-v-twin-motorcycle-rc-engine\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr\\\/p\\\/cison-fg-vt9-v-twin-motorcycle-rc-engine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.scalemonkey.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/CISON-FG-VT9-10.jpg\",\"datePublished\":\"2025-07-20T08:28:34+00:00\",\"dateModified\":\"2026-07-10T10:59:06+00:00\",\"description\":\"Moteur RC de moto bicylindre en V CISON FG-VT9 9 cm\u00b3\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr\\\/p\\\/cison-fg-vt9-v-twin-motorcycle-rc-engine\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.scalemonkey.com\\\/fr\\\/p\\\/cison-fg-vt9-v-twin-motorcycle-rc-engine\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr\\\/p\\\/cison-fg-vt9-v-twin-motorcycle-rc-engine\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/CISON-FG-VT9-10.jpg\",\"contentUrl\":\"https:\\\/\\\/www.scalemonkey.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/CISON-FG-VT9-10.jpg\",\"width\":1100,\"height\":1100},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr\\\/p\\\/cison-fg-vt9-v-twin-motorcycle-rc-engine\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boutique\",\"item\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr\\\/store\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Moteur RC de moto bicylindre en V CISON FG-VT9 9 cm\u00b3\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr\\\/\",\"name\":\"ScaleMonkey\",\"description\":\"RC-Modelle in Perfektion, Pr\u00e4zision, Leidenschaft, Innovation \u2013 das ist ScaleMonkey. Wir denken Modellbau weiter und schaffen RC-Modelle, die durch Leistung, Detailtreue und Qualit\u00e4t \u00fcberzeugen.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr\\\/#organization\",\"name\":\"ScaleMonkey\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/ScaleMonkey-mail.jpg\",\"contentUrl\":\"https:\\\/\\\/www.scalemonkey.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/ScaleMonkey-mail.jpg\",\"width\":591,\"height\":591,\"caption\":\"ScaleMonkey\"},\"image\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/scalemonkeyofficial\\\/\",\"https:\\\/\\\/www.instagram.com\\\/scalemonkey\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@scalemonkeyofficial\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Moteur RC de moto bicylindre en V CISON FG-VT9 9 cm\u00b3 | ScaleMonkey","description":"Moteur RC de moto bicylindre en V CISON FG-VT9 9 cm\u00b3","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.scalemonkey.com\/fr\/p\/cison-fg-vt9-v-twin-motorcycle-rc-engine\/","og_locale":"fr_FR","og_type":"article","og_title":"Moteur RC de moto bicylindre en V CISON FG-VT9 9 cm\u00b3 | ScaleMonkey","og_description":"Moteur RC de moto bicylindre en V CISON FG-VT9 9 cm\u00b3","og_url":"https:\/\/www.scalemonkey.com\/fr\/p\/cison-fg-vt9-v-twin-motorcycle-rc-engine\/","og_site_name":"ScaleMonkey","article_publisher":"https:\/\/www.facebook.com\/scalemonkeyofficial\/","article_modified_time":"2026-07-10T10:59:06+00:00","og_image":[{"width":1100,"height":1100,"url":"https:\/\/www.scalemonkey.com\/wp-content\/uploads\/2025\/12\/CISON-FG-VT9-10.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.scalemonkey.com\/fr\/p\/cison-fg-vt9-v-twin-motorcycle-rc-engine\/","url":"https:\/\/www.scalemonkey.com\/fr\/p\/cison-fg-vt9-v-twin-motorcycle-rc-engine\/","name":"Moteur RC de moto bicylindre en V CISON FG-VT9 9 cm\u00b3 | ScaleMonkey","isPartOf":{"@id":"https:\/\/www.scalemonkey.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.scalemonkey.com\/fr\/p\/cison-fg-vt9-v-twin-motorcycle-rc-engine\/#primaryimage"},"image":{"@id":"https:\/\/www.scalemonkey.com\/fr\/p\/cison-fg-vt9-v-twin-motorcycle-rc-engine\/#primaryimage"},"thumbnailUrl":"https:\/\/www.scalemonkey.com\/wp-content\/uploads\/2025\/12\/CISON-FG-VT9-10.jpg","datePublished":"2025-07-20T08:28:34+00:00","dateModified":"2026-07-10T10:59:06+00:00","description":"Moteur RC de moto bicylindre en V CISON FG-VT9 9 cm\u00b3","breadcrumb":{"@id":"https:\/\/www.scalemonkey.com\/fr\/p\/cison-fg-vt9-v-twin-motorcycle-rc-engine\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.scalemonkey.com\/fr\/p\/cison-fg-vt9-v-twin-motorcycle-rc-engine\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.scalemonkey.com\/fr\/p\/cison-fg-vt9-v-twin-motorcycle-rc-engine\/#primaryimage","url":"https:\/\/www.scalemonkey.com\/wp-content\/uploads\/2025\/12\/CISON-FG-VT9-10.jpg","contentUrl":"https:\/\/www.scalemonkey.com\/wp-content\/uploads\/2025\/12\/CISON-FG-VT9-10.jpg","width":1100,"height":1100},{"@type":"BreadcrumbList","@id":"https:\/\/www.scalemonkey.com\/fr\/p\/cison-fg-vt9-v-twin-motorcycle-rc-engine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.scalemonkey.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Boutique","item":"https:\/\/www.scalemonkey.com\/fr\/store\/"},{"@type":"ListItem","position":3,"name":"Moteur RC de moto bicylindre en V CISON FG-VT9 9 cm\u00b3"}]},{"@type":"WebSite","@id":"https:\/\/www.scalemonkey.com\/fr\/#website","url":"https:\/\/www.scalemonkey.com\/fr\/","name":"ScaleMonkey","description":"RC-Modelle in Perfektion, Pr\u00e4zision, Leidenschaft, Innovation \u2013 das ist ScaleMonkey. Wir denken Modellbau weiter und schaffen RC-Modelle, die durch Leistung, Detailtreue und Qualit\u00e4t \u00fcberzeugen.","publisher":{"@id":"https:\/\/www.scalemonkey.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.scalemonkey.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.scalemonkey.com\/fr\/#organization","name":"ScaleMonkey","url":"https:\/\/www.scalemonkey.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.scalemonkey.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.scalemonkey.com\/wp-content\/uploads\/2025\/11\/ScaleMonkey-mail.jpg","contentUrl":"https:\/\/www.scalemonkey.com\/wp-content\/uploads\/2025\/11\/ScaleMonkey-mail.jpg","width":591,"height":591,"caption":"ScaleMonkey"},"image":{"@id":"https:\/\/www.scalemonkey.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/scalemonkeyofficial\/","https:\/\/www.instagram.com\/scalemonkey\/","https:\/\/www.youtube.com\/@scalemonkeyofficial\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.scalemonkey.com\/fr\/wp-json\/wp\/v2\/product\/36337","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.scalemonkey.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.scalemonkey.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.scalemonkey.com\/fr\/wp-json\/wp\/v2\/comments?post=36337"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.scalemonkey.com\/fr\/wp-json\/wp\/v2\/media\/36344"}],"wp:attachment":[{"href":"https:\/\/www.scalemonkey.com\/fr\/wp-json\/wp\/v2\/media?parent=36337"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.scalemonkey.com\/fr\/wp-json\/wp\/v2\/product_cat?post=36337"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.scalemonkey.com\/fr\/wp-json\/wp\/v2\/product_tag?post=36337"},{"taxonomy":"berocket_brand","embeddable":true,"href":"https:\/\/www.scalemonkey.com\/fr\/wp-json\/wp\/v2\/berocket_brand?post=36337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}