{"id":41622,"date":"2025-11-27T05:35:18","date_gmt":"2025-11-27T04:35:18","guid":{"rendered":"https:\/\/www.scalemonkey.com\/conditions-generales\/"},"modified":"2026-07-13T22:09:19","modified_gmt":"2026-07-13T20:09:19","slug":"terms-conditions","status":"publish","type":"page","link":"https:\/\/www.scalemonkey.com\/fr-be\/terms-conditions\/","title":{"rendered":"Conditions g\u00e9n\u00e9rales"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"41622\" class=\"elementor elementor-41622 elementor-124\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1ce063ce smc-header-title e-con-full e-flex e-con e-parent\" data-id=\"1ce063ce\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-58943d56 elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"58943d56\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Conditions g\u00e9n\u00e9rales de vente<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7c49c3bf smc-page-content e-con-full e-flex e-con e-parent\" data-id=\"7c49c3bf\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1cb63fa4 smc-post-heading elementor-widget elementor-widget-heading\" data-id=\"1cb63fa4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Table des mati\u00e8res<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7788bcf2 smc-p-text-conclusion elementor-widget elementor-widget-text-editor\" data-id=\"7788bcf2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>1.<\/strong> Champ d\u2019application<br><strong>2.<\/strong> Passation de commande et conclusion du contrat<br><strong>3.<\/strong> Droit de r\u00e9tractation<br><strong>4.<\/strong> R\u00e9serve de propri\u00e9t\u00e9<br><strong>5.<\/strong> Garantie<br><strong>6.<\/strong> Responsabilit\u00e9<br><strong>7.<\/strong> Protection des donn\u00e9es<br><strong>8.<\/strong> Prix et paiement<br><strong>9.<\/strong> D\u00e9lai de livraison<br><strong>10.<\/strong> Exp\u00e9dition, assurance et transfert des risques<br><strong>11.<\/strong> Conservation et accessibilit\u00e9 du texte du contrat<br><strong>12.<\/strong> Droit applicable, juridiction comp\u00e9tente et dispositions finales<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a59d551 elementor-widget elementor-widget-spacer\" data-id=\"1a59d551\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d0f5b7e smc-post-heading elementor-widget elementor-widget-heading\" data-id=\"5d0f5b7e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">1. Champ d\u2019application<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d2f900 smc-p-text-conclusion smc-link-underline elementor-widget elementor-widget-text-editor\" data-id=\"7d2f900\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>1.1.<\/strong> Pour tous les contrats conclus via la boutique en ligne indigo-bison-747143.hostingersite.com (ci-apr\u00e8s \u00ab boutique en ligne \u00bb) entre nous, ScaleMonkey \/ Karsten M\u00f6bius, K\u00e4the-Kollwitz-Weg 73, 89081 Ulm, t\u00e9l\u00e9phone : +49 (0)731 \/ 40390785<span contenteditable=\"true\" data-elementor-setting-key=\"icon_list.0.text\" data-pen-placeholder=\"Eingabe hier...\">,<\/span> e-mail : service@scalemonkey.com (ci-apr\u00e8s \u00ab nous \u00bb ou \u00ab ScaleMonkey \u00bb), et vous (ci-apr\u00e8s \u00e9galement \u00ab client \u00bb), les conditions g\u00e9n\u00e9rales de vente suivantes (\u00ab CGV \u00bb) s\u2019appliquent exclusivement.<\/p><p><strong>1.2.<\/strong>  Le client accepte l\u2019application de ces CGV lors de son inscription \u00e0 la boutique en ligne, ou au plus tard lors de la commande de marchandises via la boutique en ligne.<\/p><p><strong>1.3.<\/strong>  L\u2019offre de marchandises dans notre boutique en ligne s\u2019adresse aussi bien aux consommateurs qu\u2019aux entrepreneurs. Aux fins des pr\u00e9sentes CGV, (I) un \u00ab consommateur \u00bb est toute personne physique qui conclut le contrat \u00e0 des fins qui ne peuvent \u00eatre imput\u00e9es principalement ni \u00e0 son activit\u00e9 commerciale ni \u00e0 son activit\u00e9 professionnelle ind\u00e9pendante (\u00a7 13 du BGB) et (II) un \u00ab entrepreneur \u00bb est une personne physique ou morale ou une soci\u00e9t\u00e9 de personnes dot\u00e9e de la capacit\u00e9 juridique qui, lors de la conclusion du contrat, agit dans l\u2019exercice de son activit\u00e9 commerciale ou professionnelle ind\u00e9pendante (\u00a7 14 al. 1 du BGB).   <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7a75d0 smc-post-heading elementor-widget elementor-widget-heading\" data-id=\"7a75d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">2. Passation de commande et conclusion du contrat<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9e27f66 smc-p-text-conclusion smc-link-underline elementor-widget elementor-widget-text-editor\" data-id=\"9e27f66\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Les offres de marchandises dans notre boutique en ligne constituent une invitation non contraignante \u00e0 commander des marchandises de mani\u00e8re ferme aupr\u00e8s de ScaleMonkey. En commandant la marchandise par un clic sur un bouton tel que \u00ab Acheter \u00bb ou \u00ab Commande avec obligation de paiement \u00bb dans la boutique en ligne, le client soumet une offre ferme pour l\u2019achat de la marchandise se trouvant dans le panier. ScaleMonkey confirmera sans d\u00e9lai la r\u00e9ception de cette commande du client par e-mail. Cette confirmation de r\u00e9ception g\u00e9n\u00e9r\u00e9e automatiquement ne constitue pas une acceptation de l\u2019offre. Le contrat avec ScaleMonkey n\u2019est conclu que par la confirmation de commande distincte de la part de ScaleMonkey par e-mail ou par la livraison de la marchandise (acceptation) ; ScaleMonkey informera toutefois le client de l\u2019acceptation de l\u2019offre dans tous les cas dans un d\u00e9lai de 5 jours ouvrables ; pass\u00e9 ce d\u00e9lai, le client n\u2019est plus li\u00e9 par son offre. La commande et la livraison ne sont possibles qu\u2019au sein de la R\u00e9publique f\u00e9d\u00e9rale d\u2019Allemagne, \u00e0 moins que nous n\u2019en ayons convenu autrement par \u00e9crit avec le client.      <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-187e7e8d smc-post-heading elementor-widget elementor-widget-heading\" data-id=\"187e7e8d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">3. Droit de r\u00e9tractation<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-792d6ebb smc-p-text-conclusion smc-link-underline elementor-widget elementor-widget-text-editor\" data-id=\"792d6ebb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>3.1. <\/strong>Information sur le droit de r\u00e9tractation<br\/>Si le client est un consommateur, il est en droit de r\u00e9voquer le contrat conform\u00e9ment aux informations sur le droit de r\u00e9tractation suivantes :<br\/>Droit de r\u00e9tractation<br\/>Vous avez le droit de vous r\u00e9tracter du pr\u00e9sent contrat sans donner de motif dans un d\u00e9lai de quatorze jours.<br\/>Le d\u00e9lai de r\u00e9tractation est de quatorze jours \u00e0 compter du jour,<br><strong>a)<\/strong> o\u00f9 vous-m\u00eame, ou un tiers autre que le transporteur et d\u00e9sign\u00e9 par vous, prenez physiquement possession des marchandises, si vous avez command\u00e9 une ou plusieurs marchandises dans le cadre d\u2019une commande unique et que la ou les marchandises sont livr\u00e9es uniform\u00e9ment ;<br\/>ou<br><strong>b)<\/strong> o\u00f9 vous-m\u00eame, ou un tiers autre que le transporteur et d\u00e9sign\u00e9 par vous, prenez physiquement possession de la derni\u00e8re marchandise, si vous avez command\u00e9 plusieurs marchandises dans le cadre d\u2019une commande unique et que les marchandises sont livr\u00e9es s\u00e9par\u00e9ment ;<br\/>ou<br><strong>c)<\/strong> o\u00f9 vous-m\u00eame, ou un tiers autre que le transporteur et d\u00e9sign\u00e9 par vous, prenez physiquement possession du dernier lot ou de la derni\u00e8re pi\u00e8ce, si vous avez command\u00e9 une marchandise livr\u00e9e en plusieurs lots ou pi\u00e8ces.<br>Si plusieurs des alternatives susmentionn\u00e9es se pr\u00e9sentent, le d\u00e9lai de r\u00e9tractation ne commence qu\u2019\u00e0 compter du jour o\u00f9 vous-m\u00eame, ou un tiers autre que le transporteur et d\u00e9sign\u00e9 par vous, prenez physiquement possession de la derni\u00e8re marchandise ou du dernier lot ou de la derni\u00e8re pi\u00e8ce.<br>Pour exercer votre droit de r\u00e9tractation, vous devez nous informer (ScaleMonkey, K\u00e4the-Kollwitz-Weg 73, 89081 Ulm, t\u00e9l\u00e9phone : +49 (0)731 \/ 40390785, e-mail : service@scalemonkey.com) de votre d\u00e9cision de vous r\u00e9tracter du pr\u00e9sent contrat au moyen d\u2019une d\u00e9claration d\u00e9nu\u00e9e d\u2019ambigu\u00eft\u00e9 (par exemple, lettre envoy\u00e9e par la poste, t\u00e9l\u00e9copie ou e-mail). Vous pouvez utiliser le mod\u00e8le de formulaire de r\u00e9tractation joint, mais ce n\u2019est pas obligatoire.<br>Vous pouvez \u00e9galement remplir et transmettre le mod\u00e8le de formulaire de r\u00e9tractation ou toute autre d\u00e9claration d\u00e9nu\u00e9e d\u2019ambigu\u00eft\u00e9 par voie \u00e9lectronique sur notre site web <a href=\"https:\/\/www.scalemonkey.com\/de\/revocation-form\">Formulaire de r\u00e9tractation<\/a>. Si vous utilisez cette option, nous vous enverrons sans d\u00e9lai (par exemple par e-mail) un accus\u00e9 de r\u00e9ception de la r\u00e9tractation.<br\/>Pour que le d\u00e9lai de r\u00e9tractation soit respect\u00e9, il suffit que vous transmettiez votre communication relative \u00e0 l\u2019exercice du droit de r\u00e9tractation avant l\u2019expiration du d\u00e9lai de r\u00e9tractation.<br\/>Cons\u00e9quences de la r\u00e9tractation<br\/>En cas de r\u00e9tractation de votre part du pr\u00e9sent contrat, nous vous rembourserons tous les paiements re\u00e7us de vous, y compris les frais de livraison (\u00e0 l\u2019exception des frais suppl\u00e9mentaires d\u00e9coulant du fait que vous avez choisi, le cas \u00e9ch\u00e9ant, un mode de livraison autre que le mode moins co\u00fbteux de livraison standard propos\u00e9 par nous) sans retard excessif et, en tout \u00e9tat de cause, au plus tard quatorze jours \u00e0 compter du jour o\u00f9 nous sommes inform\u00e9s de votre d\u00e9cision de r\u00e9tractation du pr\u00e9sent contrat. Nous proc\u00e9derons au remboursement en utilisant le m\u00eame moyen de paiement que celui que vous avez utilis\u00e9 pour la transaction initiale, sauf si vous convenez express\u00e9ment d\u2019un moyen diff\u00e9rent ; en tout \u00e9tat de cause, ce remboursement n\u2019occasionnera pas de frais pour vous. Nous pouvons diff\u00e9rer le remboursement jusqu\u2019\u00e0 ce que nous ayons re\u00e7u les marchandises ou jusqu\u2019\u00e0 ce que vous ayez fourni une preuve d\u2019exp\u00e9dition des marchandises, la date retenue \u00e9tant celle du premier de ces faits.<br\/>Vous devrez renvoyer ou rendre les marchandises \u00e0 nous-m\u00eames (ScaleMonkey, K\u00e4the-Kollwitz-Weg 73, 89081 Ulm) sans retard excessif et, en tout \u00e9tat de cause, au plus tard quatorze jours apr\u00e8s que vous nous aurez communiqu\u00e9 votre d\u00e9cision de r\u00e9tractation du pr\u00e9sent contrat. Ce d\u00e9lai est r\u00e9put\u00e9 respect\u00e9 si vous renvoyez les marchandises avant l\u2019expiration du d\u00e9lai de quatorze jours. Vous devrez prendre en charge les frais directs de renvoi des marchandises.     <\/p><p><strong>3.2.<\/strong> Exclusion du droit de r\u00e9tractation<br\/>Le droit de r\u00e9tractation ne s\u2019applique pas aux contrats<br\/>&#8211; de fourniture de marchandises confectionn\u00e9es selon les sp\u00e9cifications du consommateur ou nettement personnalis\u00e9es ;<br\/>&#8211; de fourniture de marchandises susceptibles de se d\u00e9t\u00e9riorer ou de se p\u00e9rimer rapidement ;<\/p><p><strong>3.3. <\/strong>Extinction du droit de r\u00e9tractation<br\/>Le droit de r\u00e9tractation s\u2019\u00e9teint pr\u00e9matur\u00e9ment pour les contrats<br\/>&#8211; de fourniture de marchandises qui, apr\u00e8s avoir \u00e9t\u00e9 livr\u00e9es, et de par leur nature, sont m\u00e9lang\u00e9es de mani\u00e8re indissociable avec d\u2019autres articles ;<br\/>&#8211; de fourniture d\u2019enregistrements audio ou vid\u00e9o ou de logiciels informatiques dans un emballage scell\u00e9, si le sceau a \u00e9t\u00e9 retir\u00e9 apr\u00e8s la livraison.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-311bfcd7 smc-post-heading elementor-widget elementor-widget-heading\" data-id=\"311bfcd7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">4. R\u00e9serve de propri\u00e9t\u00e9<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-638eb08f smc-p-text-conclusion smc-link-underline elementor-widget elementor-widget-text-editor\" data-id=\"638eb08f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Jusqu\u2019au paiement int\u00e9gral, la marchandise livr\u00e9e au client reste la propri\u00e9t\u00e9 de ScaleMonkey (\u00ab marchandise sous r\u00e9serve de propri\u00e9t\u00e9 \u00bb). Vous ne pouvez pas vendre ou mettre en gage cette marchandise sous r\u00e9serve de propri\u00e9t\u00e9 \u00e0 des tiers et devez la traiter de mani\u00e8re appropri\u00e9e et avec soin. Le client doit nous informer sans d\u00e9lai de tout acc\u00e8s de tiers \u00e0 la marchandise sous r\u00e9serve de propri\u00e9t\u00e9 d\u00e8s qu\u2019il en a connaissance. Le client est responsable de tous les frais engag\u00e9s pour la lev\u00e9e de tels acc\u00e8s, notamment par l\u2019introduction d\u2019une action en opposition de tiers, dans la mesure o\u00f9 le remboursement des frais ne peut \u00eatre obtenu aupr\u00e8s du tiers concern\u00e9.   <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2b202ef9 smc-post-heading elementor-widget elementor-widget-heading\" data-id=\"2b202ef9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">5. Garantie<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d56b84f smc-p-text-conclusion smc-link-underline elementor-widget elementor-widget-text-editor\" data-id=\"3d56b84f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>5.1.<\/strong>  Un droit l\u00e9gal de garantie des d\u00e9fauts s\u2019applique aux marchandises achet\u00e9es.<\/p><p><strong>5.2.<\/strong>  Si la marchandise livr\u00e9e pr\u00e9sente un d\u00e9faut mat\u00e9riel et que le client est un entrepreneur, nous pouvons choisir entre la suppression du d\u00e9faut ou la livraison d\u2019une chose exempte de d\u00e9faut. Notre choix ne peut \u00eatre effectu\u00e9 que par notification sous forme de texte (\u00e9galement par t\u00e9l\u00e9copie ou e-mail) au client dans les trois jours ouvrables suivant la notification du d\u00e9faut. <\/p><p><strong>5.3.<\/strong>  Si le client est un consommateur, ses droits au titre des d\u00e9fauts de la marchandise sont prescrits conform\u00e9ment aux dispositions l\u00e9gales. Si le client est un entrepreneur, le d\u00e9lai de prescription pour les droits du client au titre des d\u00e9fauts pour les marchandises neuves ainsi que pour les marchandises d\u2019occasion est de douze mois \u00e0 compter de la livraison de la marchandise d\u00e9fectueuse. Par d\u00e9rogation, les dispositions l\u00e9gales de prescription s\u2019appliquent dans la mesure o\u00f9 ScaleMonkey est coupable de dol, d\u2019intention d\u00e9lib\u00e9r\u00e9e ou de n\u00e9gligence grave au regard du d\u00e9faut.  <\/p><p><strong>5.4.<\/strong>  Ce qui suit s\u2019applique uniquement aux entrepreneurs : Le client doit examiner soigneusement la marchandise sans d\u00e9lai apr\u00e8s l\u2019envoi. La marchandise livr\u00e9e est consid\u00e9r\u00e9e comme accept\u00e9e par le client si un d\u00e9faut ne nous est pas signal\u00e9 (1.) dans le cas de d\u00e9fauts apparents, dans les cinq jours ouvrables suivant la livraison ou sinon (2.) dans les cinq jours ouvrables suivant la d\u00e9couverte du d\u00e9faut. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-32de00c5 smc-post-heading elementor-widget elementor-widget-heading\" data-id=\"32de00c5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">6. Responsabilit\u00e9<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4bc5fe23 smc-p-text-conclusion smc-link-underline elementor-widget elementor-widget-text-editor\" data-id=\"4bc5fe23\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>6.1.<\/strong> ScaleMonkey est responsable sans limitation<br\/>&#8211; en cas de faute intentionnelle ou de n\u00e9gligence grave,<br\/>&#8211; pour les atteintes \u00e0 la vie, \u00e0 l\u2019int\u00e9grit\u00e9 physique ou \u00e0 la sant\u00e9,<br\/>&#8211; selon les dispositions de la loi sur la responsabilit\u00e9 du fait des produits ainsi que<br\/>&#8211; dans la mesure d\u2019une garantie assum\u00e9e par ScaleMonkey.<\/p><p><strong>6.2.<\/strong>  Sans pr\u00e9judice de la disposition du point 6.1, ScaleMonkey n\u2019est responsable en cas de n\u00e9gligence qu\u2019en cas de violation d\u2019obligations contractuelles essentielles, c\u2019est-\u00e0-dire la violation d\u2019obligations dont l\u2019ex\u00e9cution permet avant tout la bonne ex\u00e9cution du contrat et sur le respect desquelles le client peut r\u00e9guli\u00e8rement compter (\u00ab obligation cardinale \u00bb). En cas de violation par n\u00e9gligence l\u00e9g\u00e8re d\u2019une obligation cardinale, la responsabilit\u00e9 de ScaleMonkey est limit\u00e9e aux dommages typiques et\/ou \u00e0 une \u00e9tendue de dommages typique qui \u00e9taient pr\u00e9visibles au moment de la conclusion du contrat. <\/p><p><strong>6.3.<\/strong>  Les limitations de responsabilit\u00e9 susmentionn\u00e9es s\u2019appliquent \u00e9galement en cas de faute d\u2019un auxiliaire d\u2019ex\u00e9cution de ScaleMonkey ainsi que pour la responsabilit\u00e9 personnelle des employ\u00e9s et repr\u00e9sentants de ScaleMonkey.<\/p><p><strong>6.4.<\/strong>  La prescription des droits \u00e0 dommages-int\u00e9r\u00eats du client se mesure, dans les cas mentionn\u00e9s au point 6.1, selon les dispositions l\u00e9gales. Le d\u00e9lai de prescription concernant les autres droits \u00e0 dommages-int\u00e9r\u00eats du client est d\u2019un an. Il commence \u00e0 la fin de l\u2019ann\u00e9e au cours de laquelle les droits sont n\u00e9s et le client a eu connaissance des circonstances fondant le droit et de la personne du d\u00e9biteur ou n\u2019en a pas eu connaissance en raison d\u2019une n\u00e9gligence grave ; toutefois, dans ces cas, les droits sont prescrits au plus tard cinq ans apr\u00e8s leur naissance et dix ans apr\u00e8s la commission de l\u2019acte, la violation de l\u2019obligation ou tout autre \u00e9v\u00e9nement ayant caus\u00e9 le dommage.  <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4392563c smc-post-heading elementor-widget elementor-widget-heading\" data-id=\"4392563c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">7. Protection des donn\u00e9es<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d1736a3 smc-p-text-conclusion smc-link-underline elementor-widget elementor-widget-text-editor\" data-id=\"6d1736a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Dans la mesure o\u00f9 des donn\u00e9es \u00e0 caract\u00e8re personnel du client sont collect\u00e9es dans le cadre de la conclusion et de l\u2019ex\u00e9cution du contrat avec le client, ScaleMonkey respectera, lors de leur traitement et de leur utilisation, les dispositions applicables en mati\u00e8re de protection des donn\u00e9es, en particulier la loi f\u00e9d\u00e9rale sur la protection des donn\u00e9es (\u00ab BDSG \u00bb). De plus amples informations sur le traitement des donn\u00e9es des clients peuvent \u00eatre consult\u00e9es dans les dispositions relatives \u00e0 la protection des donn\u00e9es de ScaleMonkey sous <a href=\"https:\/\/www.scalemonkey.com\/fr-be\/privacy-policy\/\">Protection des donn\u00e9es<\/a>. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6f96cd29 smc-post-heading elementor-widget elementor-widget-heading\" data-id=\"6f96cd29\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">8. Prix et paiement<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-44d1c6dc smc-p-text-conclusion elementor-widget elementor-widget-text-editor\" data-id=\"44d1c6dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>8.1.<\/strong>  Sauf si un autre prix a \u00e9t\u00e9 express\u00e9ment convenu dans un cas particulier, toutes les livraisons de ScaleMonkey sont effectu\u00e9es sur la base des prix indiqu\u00e9s dans la boutique en ligne le jour de la commande. Nos prix incluent la taxe sur la valeur ajout\u00e9e l\u00e9gale. \u00c0 cela s\u2019ajoutent les frais d\u2019exp\u00e9dition mentionn\u00e9s dans la commande. Les droits de douane et taxes similaires sont \u00e0 la charge du client.   <\/p><p><strong>8.2.<\/strong>  Nous livrons contre PayPal, virement imm\u00e9diat (Sofort), paiement anticip\u00e9 et sur facture pour les clients existants.<\/p><p><strong>8.3.<\/strong>  Le client ne dispose d\u2019aucun droit de compensation ou de r\u00e9tention, \u00e0 moins que la contre-cr\u00e9ance ne soit incontest\u00e9e ou constat\u00e9e judiciairement par d\u00e9cision ayant acquis force de chose jug\u00e9e.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-404a0e2 smc-post-heading elementor-widget elementor-widget-heading\" data-id=\"404a0e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">9. D\u00e9lai de livraison<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-417d09f1 smc-p-text-conclusion smc-link-underline elementor-widget elementor-widget-text-editor\" data-id=\"417d09f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>9.1.<\/strong>  Nous livrerons la marchandise au client dans le d\u00e9lai de livraison indiqu\u00e9 sur la page de l\u2019offre correspondante. Si aucun d\u00e9lai de livraison n\u2019est indiqu\u00e9 sur la page de l\u2019offre, les marchandises marqu\u00e9es comme \u00ab en stock \u00bb seront livr\u00e9es dans les dix jours ouvrables, et toutes les autres marchandises dans les quatre semaines. <\/p><p><strong>9.2.<\/strong>  Le d\u00e9lai de livraison selon le point 9.1 commence le jour de notre acceptation de la r\u00e9ception du paiement (c\u2019est-\u00e0-dire le jour de la conclusion du contrat d\u2019achat).<\/p><p><strong>9.3.<\/strong>  Si le client est un entrepreneur, ce qui suit s\u2019applique en plus : Dans le cas o\u00f9 notre fournisseur ne nous livre pas \u00e0 temps une marchandise qui \u00e9tait marqu\u00e9e comme \u00ab pas en stock \u00bb sur la page de l\u2019offre dans la boutique en ligne lors de la commande par le client, le d\u00e9lai de livraison normalement applicable selon le point 9.1 est prolong\u00e9 de la dur\u00e9e de la livraison par notre fournisseur plus deux jours ouvrables, mais au maximum d\u2019une p\u00e9riode de trois semaines. La condition pr\u00e9alable \u00e0 cette prolongation de d\u00e9lai est que nous ayons recommand\u00e9 la marchandise sans d\u00e9lai et que nous ne soyons pas responsables du retard de livraison par notre fournisseur. <\/p><p><strong>9.4.  <\/strong>Si la marchandise n\u2019est pas livrable ou ne l\u2019est pas \u00e0 temps, par exemple parce que l\u2019un de nos fournisseurs ne livre pas la marchandise \u00e0 temps, nous en informerons le client sans d\u00e9lai. Si la marchandise n\u2019est pas disponible chez nos fournisseurs dans un d\u00e9lai pr\u00e9visible, nous sommes en droit de nous r\u00e9tracter du contrat d\u2019achat. En cas de r\u00e9tractation, nous rembourserons sans d\u00e9lai au client les paiements qu\u2019il nous a vers\u00e9s. Les droits l\u00e9gaux du client en raison d\u2019un retard de livraison ne sont pas affect\u00e9s par la disposition pr\u00e9c\u00e9dente, le client ne pouvant toutefois demander des dommages-int\u00e9r\u00eats que conform\u00e9ment au point 6 des pr\u00e9sentes CGV.   <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-15be17b8 smc-post-heading elementor-widget elementor-widget-heading\" data-id=\"15be17b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">10. Exp\u00e9dition, assurance et transfert des risques<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-902d67c smc-p-text-conclusion smc-link-underline elementor-widget elementor-widget-text-editor\" data-id=\"902d67c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>10.1.<\/strong>  Sauf convention contraire expresse, nous d\u00e9terminons le mode d\u2019exp\u00e9dition appropri\u00e9 et l\u2019entreprise de transport \u00e0 notre discr\u00e9tion raisonnable.<\/p><p><strong>10.2.<\/strong>  Nous sommes autoris\u00e9s \u00e0 effectuer des livraisons partielles de marchandises utilisables s\u00e9par\u00e9ment comprises dans une commande, les frais d\u2019exp\u00e9dition suppl\u00e9mentaires en r\u00e9sultant \u00e9tant \u00e0 notre charge.<\/p><p><strong>10.3.<\/strong>  La livraison de marchandises volumineuses et encombrantes est effectu\u00e9e par un transporteur. Le transporteur livre la marchandise uniquement jusqu\u2019\u00e0 la premi\u00e8re marche ou jusqu\u2019\u00e0 la premi\u00e8re porte verrouillable \u00e0 l\u2019adresse de livraison du client. <\/p><p><strong>10.4.<\/strong>  Si le client est un entrepreneur, nous ne devons que la remise en temps voulu et en bonne et due forme de la marchandise \u00e0 l\u2019entreprise de transport et ne sommes pas responsables des retards caus\u00e9s par l\u2019entreprise de transport.<\/p><p><strong>10.5.<\/strong>  Si le client est un consommateur, le risque de perte accidentelle, de dommage accidentel ou de perte accidentelle de la marchandise livr\u00e9e est transf\u00e9r\u00e9 au client au moment o\u00f9 la marchandise est livr\u00e9e au client ou si le client est en retard d\u2019acceptation. Dans tous les autres cas, le risque est transf\u00e9r\u00e9 au client lors de la remise de la marchandise \u00e0 l\u2019entreprise de transport. <\/p><p><strong>10.6.<\/strong>  Nous assurerons la marchandise contre les risques de transport habituels \u00e0 nos frais.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5485c56b smc-post-heading elementor-widget elementor-widget-heading\" data-id=\"5485c56b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">11. Conservation et accessibilit\u00e9 du texte du contrat<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-25c99034 smc-p-text-conclusion smc-link-underline elementor-widget elementor-widget-text-editor\" data-id=\"25c99034\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Le texte du contrat est accessible au client lors de la commande et lui est envoy\u00e9 par e-mail si nous acceptons la commande. \u00c0 l\u2019exception des CGV en vigueur, les diff\u00e9rents textes contractuels ne sont pas accessibles dans la boutique en ligne apr\u00e8s la conclusion du contrat. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-305a909b smc-post-heading elementor-widget elementor-widget-heading\" data-id=\"305a909b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">12. Droit applicable, juridiction comp\u00e9tente et dispositions finales<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3455bce smc-p-text-conclusion smc-link-underline elementor-widget elementor-widget-text-editor\" data-id=\"3455bce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>12.1.<\/strong>  Le contrat d\u2019achat existant entre nous et le client ainsi que tous les droits et pr\u00e9tentions qui en d\u00e9coulent et qui y sont li\u00e9s sont soumis, sous r\u00e9serve des dispositions imp\u00e9ratives du droit international priv\u00e9, au droit de la R\u00e9publique f\u00e9d\u00e9rale d\u2019Allemagne, \u00e0 l\u2019exclusion de la Convention des Nations Unies sur les contrats de vente internationale de marchandises (CVIM).<\/p><p><strong>12.2.<\/strong>  Si le client est un commer\u00e7ant au sens du \u00a7 1 al. 1 du Code de commerce allemand (HGB), une personne morale de droit public ou un fonds sp\u00e9cial de droit public, les tribunaux d\u2019Ulm sont exclusivement comp\u00e9tents pour tous les litiges d\u00e9coulant de la relation contractuelle concern\u00e9e ou en rapport avec celle-ci. Dans tous les autres cas, nous ou le client pouvons intenter une action devant tout tribunal comp\u00e9tent en vertu des dispositions l\u00e9gales.  <\/p><p><strong>12.3.<\/strong>  Si une disposition des pr\u00e9sentes CGV \u00e9tait ou devenait invalide, ou contenait une fixation de d\u00e9lai inadmissible ou une lacune, la validit\u00e9 juridique des autres dispositions n\u2019en serait pas affect\u00e9e. Dans la mesure o\u00f9 l\u2019invalidit\u00e9 ne r\u00e9sulte pas d\u2019une violation des \u00a7\u00a7 305 et suivants du BGB (application des conditions g\u00e9n\u00e9rales de vente), une disposition valide est r\u00e9put\u00e9e convenue \u00e0 la place de la disposition invalide, laquelle se rapproche le plus \u00e9conomiquement de ce qui \u00e9tait voulu par les parties au contrat. Il en va de m\u00eame en cas de lacune. En cas de d\u00e9lai inadmissible, la mesure l\u00e9galement autoris\u00e9e s\u2019applique.   <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-21b1514e smc-p-text-conclusion elementor-widget elementor-widget-text-editor\" data-id=\"21b1514e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tLes conditions g\u00e9n\u00e9rales de vente ont \u00e9t\u00e9 mises \u00e0 jour pour la derni\u00e8re fois le  27. novembre, 2025 .\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Conditions g\u00e9n\u00e9rales de vente Table des mati\u00e8res 1. Champ d\u2019application2. Passation de commande et conclusion du contrat3. Droit de r\u00e9tractation4. R\u00e9serve de propri\u00e9t\u00e95. Garantie6. Responsabilit\u00e97. Protection des donn\u00e9es8. Prix et [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_glsr_average":0,"_glsr_ranking":0,"_glsr_reviews":0,"footnotes":""},"class_list":["post-41622","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Conditions g\u00e9n\u00e9rales | ScaleMonkey<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.scalemonkey.com\/fr-be\/terms-conditions\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conditions g\u00e9n\u00e9rales | ScaleMonkey\" \/>\n<meta property=\"og:description\" content=\"Conditions g\u00e9n\u00e9rales de vente Table des mati\u00e8res 1. Champ d\u2019application2. Passation de commande et conclusion du contrat3. Droit de r\u00e9tractation4. R\u00e9serve de propri\u00e9t\u00e95. Garantie6. Responsabilit\u00e97. Protection des donn\u00e9es8. Prix et [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.scalemonkey.com\/fr-be\/terms-conditions\/\" \/>\n<meta property=\"og:site_name\" content=\"ScaleMonkey\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/scalemonkeyofficial\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-13T20:09:19+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture est.\" \/>\n\t<meta name=\"twitter:data1\" content=\"16 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-be\\\/terms-conditions\\\/\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-be\\\/terms-conditions\\\/\",\"name\":\"Conditions g\u00e9n\u00e9rales | ScaleMonkey\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-be\\\/#website\"},\"datePublished\":\"2025-11-27T04:35:18+00:00\",\"dateModified\":\"2026-07-13T20:09:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-be\\\/terms-conditions\\\/#breadcrumb\"},\"inLanguage\":\"fr-BE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.scalemonkey.com\\\/fr-be\\\/terms-conditions\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-be\\\/terms-conditions\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-be\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conditions g\u00e9n\u00e9rales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-be\\\/#website\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-be\\\/\",\"name\":\"ScaleMonkey\",\"description\":\"RC-Modelle in Perfektion, Pr\u00e4zision, Leidenschaft, Innovation \u2013 das ist ScaleMonkey. Wir denken Modellbau weiter und schaffen RC-Modelle, die durch Leistung, Detailtreue und Qualit\u00e4t \u00fcberzeugen.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-be\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-BE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-be\\\/#organization\",\"name\":\"ScaleMonkey\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-be\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-be\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/ScaleMonkey-mail.jpg\",\"contentUrl\":\"https:\\\/\\\/www.scalemonkey.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/ScaleMonkey-mail.jpg\",\"width\":591,\"height\":591,\"caption\":\"ScaleMonkey\"},\"image\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-be\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/scalemonkeyofficial\\\/\",\"https:\\\/\\\/www.instagram.com\\\/scalemonkey\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@scalemonkeyofficial\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conditions g\u00e9n\u00e9rales | ScaleMonkey","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.scalemonkey.com\/fr-be\/terms-conditions\/","og_locale":"fr_FR","og_type":"article","og_title":"Conditions g\u00e9n\u00e9rales | ScaleMonkey","og_description":"Conditions g\u00e9n\u00e9rales de vente Table des mati\u00e8res 1. Champ d\u2019application2. Passation de commande et conclusion du contrat3. Droit de r\u00e9tractation4. R\u00e9serve de propri\u00e9t\u00e95. Garantie6. Responsabilit\u00e97. Protection des donn\u00e9es8. Prix et [&hellip;]","og_url":"https:\/\/www.scalemonkey.com\/fr-be\/terms-conditions\/","og_site_name":"ScaleMonkey","article_publisher":"https:\/\/www.facebook.com\/scalemonkeyofficial\/","article_modified_time":"2026-07-13T20:09:19+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture est.":"16 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.scalemonkey.com\/fr-be\/terms-conditions\/","url":"https:\/\/www.scalemonkey.com\/fr-be\/terms-conditions\/","name":"Conditions g\u00e9n\u00e9rales | ScaleMonkey","isPartOf":{"@id":"https:\/\/www.scalemonkey.com\/fr-be\/#website"},"datePublished":"2025-11-27T04:35:18+00:00","dateModified":"2026-07-13T20:09:19+00:00","breadcrumb":{"@id":"https:\/\/www.scalemonkey.com\/fr-be\/terms-conditions\/#breadcrumb"},"inLanguage":"fr-BE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.scalemonkey.com\/fr-be\/terms-conditions\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.scalemonkey.com\/fr-be\/terms-conditions\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.scalemonkey.com\/fr-be\/home\/"},{"@type":"ListItem","position":2,"name":"Conditions g\u00e9n\u00e9rales"}]},{"@type":"WebSite","@id":"https:\/\/www.scalemonkey.com\/fr-be\/#website","url":"https:\/\/www.scalemonkey.com\/fr-be\/","name":"ScaleMonkey","description":"RC-Modelle in Perfektion, Pr\u00e4zision, Leidenschaft, Innovation \u2013 das ist ScaleMonkey. Wir denken Modellbau weiter und schaffen RC-Modelle, die durch Leistung, Detailtreue und Qualit\u00e4t \u00fcberzeugen.","publisher":{"@id":"https:\/\/www.scalemonkey.com\/fr-be\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.scalemonkey.com\/fr-be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-BE"},{"@type":"Organization","@id":"https:\/\/www.scalemonkey.com\/fr-be\/#organization","name":"ScaleMonkey","url":"https:\/\/www.scalemonkey.com\/fr-be\/","logo":{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/www.scalemonkey.com\/fr-be\/#\/schema\/logo\/image\/","url":"https:\/\/www.scalemonkey.com\/wp-content\/uploads\/2025\/11\/ScaleMonkey-mail.jpg","contentUrl":"https:\/\/www.scalemonkey.com\/wp-content\/uploads\/2025\/11\/ScaleMonkey-mail.jpg","width":591,"height":591,"caption":"ScaleMonkey"},"image":{"@id":"https:\/\/www.scalemonkey.com\/fr-be\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/scalemonkeyofficial\/","https:\/\/www.instagram.com\/scalemonkey\/","https:\/\/www.youtube.com\/@scalemonkeyofficial\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.scalemonkey.com\/fr-be\/wp-json\/wp\/v2\/pages\/41622","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.scalemonkey.com\/fr-be\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.scalemonkey.com\/fr-be\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.scalemonkey.com\/fr-be\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.scalemonkey.com\/fr-be\/wp-json\/wp\/v2\/comments?post=41622"}],"version-history":[{"count":0,"href":"https:\/\/www.scalemonkey.com\/fr-be\/wp-json\/wp\/v2\/pages\/41622\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.scalemonkey.com\/fr-be\/wp-json\/wp\/v2\/media?parent=41622"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}