{"id":2869,"count":0,"description":"","link":"https:\/\/www.scalemonkey.com\/en\/store\/uncategorized\/","name":"Uncategorized","slug":"uncategorized","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Uncategorized-Archiv | scalemonkey.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.scalemonkey.com\/en\/store\/uncategorized\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Uncategorized-Archiv | scalemonkey.com\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.scalemonkey.com\/en\/store\/uncategorized\/\" \/>\n<meta property=\"og:site_name\" content=\"scalemonkey.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/en\\\/store\\\/uncategorized\\\/\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/en\\\/store\\\/uncategorized\\\/\",\"name\":\"Uncategorized-Archiv | scalemonkey.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/en\\\/store\\\/uncategorized\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/en\\\/store\\\/uncategorized\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Start\",\"item\":\"https:\\\/\\\/www.scalemonkey.com\\\/en\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uncategorized\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/en\\\/\",\"name\":\"ScaleMonkey\",\"description\":\"Anspruchsvoller RC-Modellbau, eigene Baus\u00e4tze, Rolling-Chassis, Upgrades und Zubeh\u00f6r.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.scalemonkey.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/en\\\/#organization\",\"name\":\"ScaleMonkey\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/ScaleMonkey-mail.jpg\",\"contentUrl\":\"https:\\\/\\\/www.scalemonkey.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/ScaleMonkey-mail.jpg\",\"width\":591,\"height\":591,\"caption\":\"ScaleMonkey\"},\"image\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/scalemonkey\\\/\",\"https:\\\/\\\/www.instagram.com\\\/scalemonkey\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@scalemonkeyofficial\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Uncategorized-Archiv | scalemonkey.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.scalemonkey.com\/en\/store\/uncategorized\/","og_locale":"en_GB","og_type":"article","og_title":"Uncategorized-Archiv | scalemonkey.com","og_url":"https:\/\/www.scalemonkey.com\/en\/store\/uncategorized\/","og_site_name":"scalemonkey.com","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.scalemonkey.com\/en\/store\/uncategorized\/","url":"https:\/\/www.scalemonkey.com\/en\/store\/uncategorized\/","name":"Uncategorized-Archiv | scalemonkey.com","isPartOf":{"@id":"https:\/\/www.scalemonkey.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.scalemonkey.com\/en\/store\/uncategorized\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/www.scalemonkey.com\/en\/store\/uncategorized\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Start","item":"https:\/\/www.scalemonkey.com\/en\/home\/"},{"@type":"ListItem","position":2,"name":"Uncategorized"}]},{"@type":"WebSite","@id":"https:\/\/www.scalemonkey.com\/en\/#website","url":"https:\/\/www.scalemonkey.com\/en\/","name":"ScaleMonkey","description":"Anspruchsvoller RC-Modellbau, eigene Baus\u00e4tze, Rolling-Chassis, Upgrades und Zubeh\u00f6r.","publisher":{"@id":"https:\/\/www.scalemonkey.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.scalemonkey.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.scalemonkey.com\/en\/#organization","name":"ScaleMonkey","url":"https:\/\/www.scalemonkey.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.scalemonkey.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.scalemonkey.com\/wp-content\/uploads\/2026\/08\/ScaleMonkey-mail.jpg","contentUrl":"https:\/\/www.scalemonkey.com\/wp-content\/uploads\/2026\/08\/ScaleMonkey-mail.jpg","width":591,"height":591,"caption":"ScaleMonkey"},"image":{"@id":"https:\/\/www.scalemonkey.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/scalemonkey\/","https:\/\/www.instagram.com\/scalemonkey\/","https:\/\/www.youtube.com\/@scalemonkeyofficial\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.scalemonkey.com\/en\/wp-json\/wp\/v2\/product_cat\/2869","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.scalemonkey.com\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.scalemonkey.com\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/www.scalemonkey.com\/en\/wp-json\/wp\/v2\/product?product_cat=2869"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}