{"id":34657,"date":"2025-07-20T10:28:34","date_gmt":"2025-07-20T08:28:34","guid":{"rendered":"https:\/\/www.scalemonkey.com\/p\/cison-fg-vt9-v-twin-motorcycle-rc-engine\/"},"modified":"2026-07-10T12:59:01","modified_gmt":"2026-07-10T10:59:01","slug":"cison-fg-vt9-v-twin-motorcycle-rc-engine","status":"publish","type":"product","link":"https:\/\/www.scalemonkey.com\/de-ch\/p\/cison-fg-vt9-v-twin-motorcycle-rc-engine\/","title":{"rendered":"<div class=\"bapl_ajax_replace bapl_ajax_tleft\" style=\"display:none;\" data-id=\"34657\"><\/div>CISON FG-VT9 9cc V-twin Motorcycle RC Engine<div class=\"bapl_ajax_replace bapl_ajax_tright\" style=\"display:none;\" data-id=\"34657\"><\/div>"},"content":{"rendered":"<p>CISON FG-VT9 9cc V-twin V2 Motor luftgek\u00fchlt Motorrad RC Benzinmotor.<\/p>\n<p><em>Neueste Version!<\/em><\/p>\n<p><strong class=\"smc-description-note\">Wichtigste Verbesserungen in der neuen Version (FG-18VTP):<\/strong><\/p>\n<ul>\n<li>Hubraumerh\u00f6hung : Urspr\u00fcnglich 9 cm\u00b3 , sp\u00e4ter auf 15,7 cm\u00b3 und nun auf 18,2 cm\u00b3 erweitert f\u00fcr mehr Leistung und einen ruhigeren Lauf.<\/li>\n<li>Gr\u00f6\u00dfere Bohrung : Von 16,67 mm auf 20 mm vergr\u00f6\u00dfert f\u00fcr eine verbesserte Verbrennung.<\/li>\n<li>Verl\u00e4ngerter Hub : Von 21 mm auf 29 mm verl\u00e4ngert f\u00fcr mehr Drehmoment und bessere Gesamtleistung.<\/li>\n<li>Verbesserte Abgasanlage : Das bisherige Edelstahl-Auspuffrohr wurde durch eine 3D-gedruckte Auspuffanlage ersetzt , die leichter und eleganter ist.<\/li>\n<\/ul>\n<p>Ein V2-Motor, auch V-Twin genannt, ist ein Zweizylindermotor, bei dem die Zylinder ein \u201eV\u201c bilden. Er wird auch als Panhead-Motor bezeichnet, da es sich um einen h\u00e4ngenden Motorradmotor von Harley-Davidson handelt, der so genannt wird, weil die Kipphebelabdeckungen an Kocht\u00f6pfe erinnern. Die Motoren sind in V-Anordnung mit Winkeln gr\u00f6\u00dfer als 0, aber kleiner als 180 Grad angeordnet. Manchmal k\u00f6nnen die Zylinder einen Winkel von 90 Grad bilden, was als L-Twin bezeichnet wird. Diese Motoren werden haupts\u00e4chlich wegen ihrer kompakten Gr\u00f6\u00dfe, ihres hohen Verh\u00e4ltnisses von Leistung zu Hubraum und ihres niedrigen Leistungs-\/Drehmomentverh\u00e4ltnisses verwendet. Seit den sp\u00e4ten 1880er Jahren werden V2-Motoren auch in Motorr\u00e4dern und einigen Kleinwagen eingesetzt. Die am weitesten verbreiteten V-Twin-Motoren sind die 45\u00b0-Motorr\u00e4der von Harley Davidson, von denen die meisten luftgek\u00fchlt sind, aber es gibt auch Motoren mit Wassermantel und den wassergek\u00fchlten VRod-Motor. Vibrationen werden oft mit dem Mythos des V-Twins in Verbindung gebracht, sind aber ein ungl\u00fccklicher Nebeneffekt der beliebtesten Konstruktion. Harley platzierte die beiden Zylinder in einem Winkel von 45 Grad zueinander auf einem gemeinsamen Kurbelgeh\u00e4use, damit der Motor in einen fahrrad\u00e4hnlichen Rahmen passte, der urspr\u00fcnglich f\u00fcr einen Einzylinder-Motor vorgesehen war. Leider hat ein V-Winkel von 45 Grad eine ausgepr\u00e4gte Vibrationssignatur\u201c. Die meisten Motorenexperten sind sich einig, dass die Seele des V-Twins im Vibrieren und Zittern des Motorraums liegt. Es besteht kein Zweifel, dass die meisten Motorkenner der Meinung sind, dass die Seele des V-Twins im Zittern und Beben des Motorraums liegt.<\/p>\n<pre>Lieferumfang:<\/pre>\n<ul>\n<li><strong>Motor einzel:<\/strong> Motor komplett montiert mit Z\u00fcndanlage und Auspuffrohren<\/li>\n<li><strong>Motor mit Holzsockel:<\/strong> Motor komplett montiert auf Holzsockel mit Z\u00fcndanlage, Auspuffrohren, Tank und Elektronikzubeh\u00f6r<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" title=\"Cison FG-VT9  9ccm V2 V-Twin RC Engine\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/8rnSE7nilbE?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Beeindruckende Detailtreue:<\/strong><br \/>\nDie authentische Kipphebelabdeckung auf dem klassischen Zylinderkopf und der Getriebeabdeckung erm\u00f6glicht es dem Modell, den urspr\u00fcnglichen Charme wiederherzustellen und dem Motorradmotor in der Realit\u00e4t n\u00e4her zu kommen, wobei die bemerkenswertesten Merkmale eines Motorrads in einer \u00c4ra dargestellt werden.<\/p>\n<p><strong>Kompatibel mit RC-Fahrzeugen:<\/strong><br \/>\nVerf\u00fcgt \u00fcber einen gr\u00f6\u00dferen Zylinderdurchmesser und einen l\u00e4ngeren Hub f\u00fcr eine bessere Verdr\u00e4ngung, zusammen mit st\u00e4rkeren Pleuelstangen, um einen hervorragenden Drehmomentschutz zu bieten, wenn sie auf den Fahrzeugen installiert sind.<\/p>\n<p><strong>Zuverl\u00e4ssige Konstruktion:<\/strong><br \/>\nVerwendet einen OHV-Ventilmechanismus, einen 45\u00b0-Winkel zwischen zwei Zylindern, eine realistische halbkugelf\u00f6rmige Verbrennungskammer, einen Einlasskipphebel mit einem V-f\u00f6rmigen Winkel sowie eine abnehmbare Kipphebelabdeckungskammer zur leichteren Beobachtung und Einstellung des Motors.<\/p>\n<p><strong>Zuverl\u00e4ssige und hohe Leistung:<\/strong><br \/>\nAusgestattet mit einem gro\u00dffl\u00e4chigen K\u00fchlk\u00f6rper f\u00fcr unglaubliche Luftk\u00fchlungseffekte, ist der Motor in der Lage, stabil zu arbeiten, indem er niedrige Geschwindigkeiten beibeh\u00e4lt, und unterst\u00fctzt die Verwendung verschiedener Kraftstoffe f\u00fcr eine gleichm\u00e4\u00dfigere Verbrennung dank des optimierten Vergasers.<\/p>\n<div class=\"smc-import-note\" style=\"text-align: center;\"><strong>Hinweis zur Lieferzeit:<\/strong><br \/>\nDieser Artikel wird und auf Kundenbestellung importiert. Daher kann es vereinzelt zu kleinen Abweichungen bei der Lieferzeit kommen. Wir geben unser Bestes, die angegebenen Lieferzeiten einzuhalten, und informieren dich selbstverst\u00e4ndlich \u00fcber den aktuellen Status deiner Bestellung.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>CISON FG-VT9 9cc V-twin V2 Motor luftgek\u00fchlt Motorrad RC Benzinmotor. Neueste Version! Wichtigste Verbesserungen in der neuen Version (FG-18VTP): Hubraumerh\u00f6hung : Urspr\u00fcnglich 9 cm\u00b3 , sp\u00e4ter auf 15,7 cm\u00b3 und [&hellip;]<\/p>\n","protected":false},"featured_media":34658,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_glsr_average":0,"_glsr_ranking":0,"_glsr_reviews":0},"product_cat":[515],"product_tag":[429],"berocket_brand":[517],"class_list":["post-34657","product","type-product","status-publish","has-post-thumbnail","product_cat-four-stroke-engine","product_tag-v2-engines","product_shipping_class-standard-shipping","berocket_brand-cison-engine","first","instock","taxable","shipping-taxable","purchasable","product-type-variable","wvs-archive-product-wrapper"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CISON FG-VT9 9cc V-twin Motorcycle RC Engine | ScaleMonkey<\/title>\n<meta name=\"description\" content=\"CISON FG-VT9 9cc V-twin Motorcycle RC Engine\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.scalemonkey.com\/de-ch\/p\/cison-fg-vt9-v-twin-motorcycle-rc-engine\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CISON FG-VT9 9cc V-twin Motorcycle RC Engine | ScaleMonkey\" \/>\n<meta property=\"og:description\" content=\"CISON FG-VT9 9cc V-twin Motorcycle RC Engine\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.scalemonkey.com\/de-ch\/p\/cison-fg-vt9-v-twin-motorcycle-rc-engine\/\" \/>\n<meta property=\"og:site_name\" content=\"ScaleMonkey\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/scalemonkeyofficial\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-10T10:59:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.scalemonkey.com\/wp-content\/uploads\/2025\/12\/CISON-FG-VT9-10.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1100\" \/>\n\t<meta property=\"og:image:height\" content=\"1100\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/de-ch\\\/p\\\/cison-fg-vt9-v-twin-motorcycle-rc-engine\\\/\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/de-ch\\\/p\\\/cison-fg-vt9-v-twin-motorcycle-rc-engine\\\/\",\"name\":\"CISON FG-VT9 9cc V-twin Motorcycle RC Engine | ScaleMonkey\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/de-ch\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/de-ch\\\/p\\\/cison-fg-vt9-v-twin-motorcycle-rc-engine\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/de-ch\\\/p\\\/cison-fg-vt9-v-twin-motorcycle-rc-engine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.scalemonkey.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/CISON-FG-VT9-10.jpg\",\"datePublished\":\"2025-07-20T08:28:34+00:00\",\"dateModified\":\"2026-07-10T10:59:01+00:00\",\"description\":\"CISON FG-VT9 9cc V-twin Motorcycle RC Engine\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/de-ch\\\/p\\\/cison-fg-vt9-v-twin-motorcycle-rc-engine\\\/#breadcrumb\"},\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.scalemonkey.com\\\/de-ch\\\/p\\\/cison-fg-vt9-v-twin-motorcycle-rc-engine\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/de-ch\\\/p\\\/cison-fg-vt9-v-twin-motorcycle-rc-engine\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/CISON-FG-VT9-10.jpg\",\"contentUrl\":\"https:\\\/\\\/www.scalemonkey.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/CISON-FG-VT9-10.jpg\",\"width\":1100,\"height\":1100},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/de-ch\\\/p\\\/cison-fg-vt9-v-twin-motorcycle-rc-engine\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.scalemonkey.com\\\/de-ch\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Store\",\"item\":\"https:\\\/\\\/www.scalemonkey.com\\\/de-ch\\\/store\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"CISON FG-VT9 9cc V-twin Motorcycle RC Engine\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/de-ch\\\/#website\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/de-ch\\\/\",\"name\":\"ScaleMonkey\",\"description\":\"RC-Modelle in Perfektion, Pr\u00e4zision, Leidenschaft, Innovation \u2013 das ist ScaleMonkey. Wir denken Modellbau weiter und schaffen RC-Modelle, die durch Leistung, Detailtreue und Qualit\u00e4t \u00fcberzeugen.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/de-ch\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.scalemonkey.com\\\/de-ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-CH\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/de-ch\\\/#organization\",\"name\":\"ScaleMonkey\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/de-ch\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/de-ch\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/ScaleMonkey-mail.jpg\",\"contentUrl\":\"https:\\\/\\\/www.scalemonkey.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/ScaleMonkey-mail.jpg\",\"width\":591,\"height\":591,\"caption\":\"ScaleMonkey\"},\"image\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/de-ch\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/scalemonkeyofficial\\\/\",\"https:\\\/\\\/www.instagram.com\\\/scalemonkey\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@scalemonkeyofficial\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CISON FG-VT9 9cc V-twin Motorcycle RC Engine | ScaleMonkey","description":"CISON FG-VT9 9cc V-twin Motorcycle RC Engine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.scalemonkey.com\/de-ch\/p\/cison-fg-vt9-v-twin-motorcycle-rc-engine\/","og_locale":"de_DE","og_type":"article","og_title":"CISON FG-VT9 9cc V-twin Motorcycle RC Engine | ScaleMonkey","og_description":"CISON FG-VT9 9cc V-twin Motorcycle RC Engine","og_url":"https:\/\/www.scalemonkey.com\/de-ch\/p\/cison-fg-vt9-v-twin-motorcycle-rc-engine\/","og_site_name":"ScaleMonkey","article_publisher":"https:\/\/www.facebook.com\/scalemonkeyofficial\/","article_modified_time":"2026-07-10T10:59:01+00:00","og_image":[{"width":1100,"height":1100,"url":"https:\/\/www.scalemonkey.com\/wp-content\/uploads\/2025\/12\/CISON-FG-VT9-10.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.scalemonkey.com\/de-ch\/p\/cison-fg-vt9-v-twin-motorcycle-rc-engine\/","url":"https:\/\/www.scalemonkey.com\/de-ch\/p\/cison-fg-vt9-v-twin-motorcycle-rc-engine\/","name":"CISON FG-VT9 9cc V-twin Motorcycle RC Engine | ScaleMonkey","isPartOf":{"@id":"https:\/\/www.scalemonkey.com\/de-ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.scalemonkey.com\/de-ch\/p\/cison-fg-vt9-v-twin-motorcycle-rc-engine\/#primaryimage"},"image":{"@id":"https:\/\/www.scalemonkey.com\/de-ch\/p\/cison-fg-vt9-v-twin-motorcycle-rc-engine\/#primaryimage"},"thumbnailUrl":"https:\/\/www.scalemonkey.com\/wp-content\/uploads\/2025\/12\/CISON-FG-VT9-10.jpg","datePublished":"2025-07-20T08:28:34+00:00","dateModified":"2026-07-10T10:59:01+00:00","description":"CISON FG-VT9 9cc V-twin Motorcycle RC Engine","breadcrumb":{"@id":"https:\/\/www.scalemonkey.com\/de-ch\/p\/cison-fg-vt9-v-twin-motorcycle-rc-engine\/#breadcrumb"},"inLanguage":"de-CH","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.scalemonkey.com\/de-ch\/p\/cison-fg-vt9-v-twin-motorcycle-rc-engine\/"]}]},{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/www.scalemonkey.com\/de-ch\/p\/cison-fg-vt9-v-twin-motorcycle-rc-engine\/#primaryimage","url":"https:\/\/www.scalemonkey.com\/wp-content\/uploads\/2025\/12\/CISON-FG-VT9-10.jpg","contentUrl":"https:\/\/www.scalemonkey.com\/wp-content\/uploads\/2025\/12\/CISON-FG-VT9-10.jpg","width":1100,"height":1100},{"@type":"BreadcrumbList","@id":"https:\/\/www.scalemonkey.com\/de-ch\/p\/cison-fg-vt9-v-twin-motorcycle-rc-engine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.scalemonkey.com\/de-ch\/home\/"},{"@type":"ListItem","position":2,"name":"Store","item":"https:\/\/www.scalemonkey.com\/de-ch\/store\/"},{"@type":"ListItem","position":3,"name":"CISON FG-VT9 9cc V-twin Motorcycle RC Engine"}]},{"@type":"WebSite","@id":"https:\/\/www.scalemonkey.com\/de-ch\/#website","url":"https:\/\/www.scalemonkey.com\/de-ch\/","name":"ScaleMonkey","description":"RC-Modelle in Perfektion, Pr\u00e4zision, Leidenschaft, Innovation \u2013 das ist ScaleMonkey. Wir denken Modellbau weiter und schaffen RC-Modelle, die durch Leistung, Detailtreue und Qualit\u00e4t \u00fcberzeugen.","publisher":{"@id":"https:\/\/www.scalemonkey.com\/de-ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.scalemonkey.com\/de-ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-CH"},{"@type":"Organization","@id":"https:\/\/www.scalemonkey.com\/de-ch\/#organization","name":"ScaleMonkey","url":"https:\/\/www.scalemonkey.com\/de-ch\/","logo":{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/www.scalemonkey.com\/de-ch\/#\/schema\/logo\/image\/","url":"https:\/\/www.scalemonkey.com\/wp-content\/uploads\/2025\/11\/ScaleMonkey-mail.jpg","contentUrl":"https:\/\/www.scalemonkey.com\/wp-content\/uploads\/2025\/11\/ScaleMonkey-mail.jpg","width":591,"height":591,"caption":"ScaleMonkey"},"image":{"@id":"https:\/\/www.scalemonkey.com\/de-ch\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/scalemonkeyofficial\/","https:\/\/www.instagram.com\/scalemonkey\/","https:\/\/www.youtube.com\/@scalemonkeyofficial\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.scalemonkey.com\/de-ch\/wp-json\/wp\/v2\/product\/34657","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.scalemonkey.com\/de-ch\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.scalemonkey.com\/de-ch\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.scalemonkey.com\/de-ch\/wp-json\/wp\/v2\/comments?post=34657"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.scalemonkey.com\/de-ch\/wp-json\/wp\/v2\/media\/34658"}],"wp:attachment":[{"href":"https:\/\/www.scalemonkey.com\/de-ch\/wp-json\/wp\/v2\/media?parent=34657"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.scalemonkey.com\/de-ch\/wp-json\/wp\/v2\/product_cat?post=34657"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.scalemonkey.com\/de-ch\/wp-json\/wp\/v2\/product_tag?post=34657"},{"taxonomy":"berocket_brand","embeddable":true,"href":"https:\/\/www.scalemonkey.com\/de-ch\/wp-json\/wp\/v2\/berocket_brand?post=34657"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}