{"id":5847,"count":0,"description":"<h2 class=\"smc-custom-heading\">Rondelles<span class=\"smc-newline-separator\">Pour que l\u2019assemblage soit parfait<\/span><\/h2>\nLes rondelles font partie de ces composants discrets qui ne doivent pas manquer dans un bon vissage. Elles r\u00e9partissent les forces, cr\u00e9ent des surfaces d\u2019appui d\u00e9finies et aident \u00e0 fixer les composants de mani\u00e8re fiable. \n\nChez ScaleMonkey, tu trouveras des rondelles pour le mod\u00e9lisme et le RC \u2013 adapt\u00e9es \u00e0 nos vis, \u00e9crous et autres \u00e9l\u00e9ments de fixation.\n\nQue ce soit sur le ch\u00e2ssis, le train roulant, la carrosserie ou des constructions individuelles&nbsp;: la bonne rondelle cr\u00e9e une solution techniquement coh\u00e9rente l\u00e0 o\u00f9 quelques millim\u00e8tres font la diff\u00e9rence.\n\n<strong>Discr\u00e8te. Jusqu\u2019\u00e0 ce qu\u2019elle manque. <\/strong>","link":"https:\/\/www.scalemonkey.com\/fr-ca\/store\/garage-tools\/hardware\/washers\/","name":"Rondelles","slug":"washers","taxonomy":"product_cat","parent":5844,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rondelles-Archiv | scalemonkey.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.scalemonkey.com\/fr-ca\/store\/garage-tools\/hardware\/washers\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rondelles-Archiv | scalemonkey.com\" \/>\n<meta property=\"og:description\" content=\"RondellesPour que l\u2019assemblage soit parfait Les rondelles font partie de ces composants discrets qui ne doivent pas manquer dans un bon vissage. Elles r\u00e9partissent les forces, cr\u00e9ent des surfaces d\u2019appui d\u00e9finies et aident \u00e0 fixer les composants de mani\u00e8re fiable. Chez ScaleMonkey, tu trouveras des rondelles pour le mod\u00e9lisme et le RC \u2013 adapt\u00e9es \u00e0 nos vis, \u00e9crous et autres \u00e9l\u00e9ments de fixation. Que ce soit sur le ch\u00e2ssis, le train roulant, la carrosserie ou des constructions individuelles&nbsp;: la bonne rondelle cr\u00e9e une solution techniquement coh\u00e9rente l\u00e0 o\u00f9 quelques millim\u00e8tres font la diff\u00e9rence. Discr\u00e8te. Jusqu\u2019\u00e0 ce qu\u2019elle manque.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.scalemonkey.com\/fr-ca\/store\/garage-tools\/hardware\/washers\/\" \/>\n<meta property=\"og:site_name\" content=\"scalemonkey.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-ca\\\/store\\\/garage-tools\\\/hardware\\\/washers\\\/\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-ca\\\/store\\\/garage-tools\\\/hardware\\\/washers\\\/\",\"name\":\"Rondelles-Archiv | scalemonkey.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-ca\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-ca\\\/store\\\/garage-tools\\\/hardware\\\/washers\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-ca\\\/store\\\/garage-tools\\\/hardware\\\/washers\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Start\",\"item\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-ca\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rondelles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-ca\\\/#website\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-ca\\\/\",\"name\":\"ScaleMonkey\",\"description\":\"Anspruchsvoller RC-Modellbau, eigene Baus\u00e4tze, Rolling-Chassis, Upgrades und Zubeh\u00f6r.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-ca\\\/#organization\",\"name\":\"ScaleMonkey\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/ScaleMonkey-mail.jpg\",\"contentUrl\":\"https:\\\/\\\/www.scalemonkey.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/ScaleMonkey-mail.jpg\",\"width\":591,\"height\":591,\"caption\":\"ScaleMonkey\"},\"image\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/scalemonkey\\\/\",\"https:\\\/\\\/www.instagram.com\\\/scalemonkey\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@scalemonkeyofficial\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rondelles-Archiv | scalemonkey.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.scalemonkey.com\/fr-ca\/store\/garage-tools\/hardware\/washers\/","og_locale":"fr_CA","og_type":"article","og_title":"Rondelles-Archiv | scalemonkey.com","og_description":"RondellesPour que l\u2019assemblage soit parfait Les rondelles font partie de ces composants discrets qui ne doivent pas manquer dans un bon vissage. Elles r\u00e9partissent les forces, cr\u00e9ent des surfaces d\u2019appui d\u00e9finies et aident \u00e0 fixer les composants de mani\u00e8re fiable. Chez ScaleMonkey, tu trouveras des rondelles pour le mod\u00e9lisme et le RC \u2013 adapt\u00e9es \u00e0 nos vis, \u00e9crous et autres \u00e9l\u00e9ments de fixation. Que ce soit sur le ch\u00e2ssis, le train roulant, la carrosserie ou des constructions individuelles&nbsp;: la bonne rondelle cr\u00e9e une solution techniquement coh\u00e9rente l\u00e0 o\u00f9 quelques millim\u00e8tres font la diff\u00e9rence. Discr\u00e8te. Jusqu\u2019\u00e0 ce qu\u2019elle manque.","og_url":"https:\/\/www.scalemonkey.com\/fr-ca\/store\/garage-tools\/hardware\/washers\/","og_site_name":"scalemonkey.com","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.scalemonkey.com\/fr-ca\/store\/garage-tools\/hardware\/washers\/","url":"https:\/\/www.scalemonkey.com\/fr-ca\/store\/garage-tools\/hardware\/washers\/","name":"Rondelles-Archiv | scalemonkey.com","isPartOf":{"@id":"https:\/\/www.scalemonkey.com\/fr-ca\/#website"},"breadcrumb":{"@id":"https:\/\/www.scalemonkey.com\/fr-ca\/store\/garage-tools\/hardware\/washers\/#breadcrumb"},"inLanguage":"fr-CA"},{"@type":"BreadcrumbList","@id":"https:\/\/www.scalemonkey.com\/fr-ca\/store\/garage-tools\/hardware\/washers\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Start","item":"https:\/\/www.scalemonkey.com\/fr-ca\/home\/"},{"@type":"ListItem","position":2,"name":"Rondelles"}]},{"@type":"WebSite","@id":"https:\/\/www.scalemonkey.com\/fr-ca\/#website","url":"https:\/\/www.scalemonkey.com\/fr-ca\/","name":"ScaleMonkey","description":"Anspruchsvoller RC-Modellbau, eigene Baus\u00e4tze, Rolling-Chassis, Upgrades und Zubeh\u00f6r.","publisher":{"@id":"https:\/\/www.scalemonkey.com\/fr-ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.scalemonkey.com\/fr-ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/www.scalemonkey.com\/fr-ca\/#organization","name":"ScaleMonkey","url":"https:\/\/www.scalemonkey.com\/fr-ca\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/www.scalemonkey.com\/fr-ca\/#\/schema\/logo\/image\/","url":"https:\/\/www.scalemonkey.com\/wp-content\/uploads\/2026\/08\/ScaleMonkey-mail.jpg","contentUrl":"https:\/\/www.scalemonkey.com\/wp-content\/uploads\/2026\/08\/ScaleMonkey-mail.jpg","width":591,"height":591,"caption":"ScaleMonkey"},"image":{"@id":"https:\/\/www.scalemonkey.com\/fr-ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/scalemonkey\/","https:\/\/www.instagram.com\/scalemonkey\/","https:\/\/www.youtube.com\/@scalemonkeyofficial\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.scalemonkey.com\/fr-ca\/wp-json\/wp\/v2\/product_cat\/5847","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.scalemonkey.com\/fr-ca\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.scalemonkey.com\/fr-ca\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/www.scalemonkey.com\/fr-ca\/wp-json\/wp\/v2\/product_cat\/5844"}],"wp:post_type":[{"href":"https:\/\/www.scalemonkey.com\/fr-ca\/wp-json\/wp\/v2\/product?product_cat=5847"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}