{"id":6138,"count":0,"description":"<h2 class=\"smc-custom-heading\">H\u00e9lices<span class=\"smc-newline-separator\">L\u00e0 o\u00f9 la puissance devient propulsion<\/span><\/h2>\nL\u2019h\u00e9lice est le dernier maillon de la cha\u00eene de propulsion \u2014 et l\u2019un des plus d\u00e9cisifs. Seul le bon accord entre moteur, r\u00e9gime, diam\u00e8tre d\u2019h\u00e9lice et pas permet de transmettre efficacement la puissance disponible \u00e0 l\u2019eau. \n\nChez ScaleMonkey, tu trouveras des h\u00e9lices s\u00e9lectionn\u00e9es pour diff\u00e9rents mod\u00e8les et concepts de propulsion. Il ne s\u2019agit pas simplement d\u2019avoir un maximum de pouss\u00e9e. Une h\u00e9lice bien accord\u00e9e doit correspondre au moteur, \u00e0 la taille et au poids du mod\u00e8le, ainsi qu\u2019au comportement recherch\u00e9.  \n\nDu mod\u00e8le scale fid\u00e8le \u00e0 l\u2019original au bateau RC orient\u00e9 performance : le bon choix d\u2019h\u00e9lice influence l\u2019acc\u00e9l\u00e9ration, la vitesse, la consommation de courant et, enfin, l\u2019allure sur l\u2019eau.\n\n<strong>Parce que la puissance ne compte que lorsqu\u2019elle arrive dans l\u2019eau.<\/strong>","link":"https:\/\/www.scalemonkey.com\/fr-be\/store\/model-building\/model-boats\/propellers\/","name":"H\u00e9lices","slug":"propellers","taxonomy":"product_cat","parent":6135,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>H\u00e9lices-Archiv | scalemonkey.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.scalemonkey.com\/fr-be\/store\/model-building\/model-boats\/propellers\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"H\u00e9lices-Archiv | scalemonkey.com\" \/>\n<meta property=\"og:description\" content=\"H\u00e9licesL\u00e0 o\u00f9 la puissance devient propulsion L\u2019h\u00e9lice est le dernier maillon de la cha\u00eene de propulsion \u2014 et l\u2019un des plus d\u00e9cisifs. Seul le bon accord entre moteur, r\u00e9gime, diam\u00e8tre d\u2019h\u00e9lice et pas permet de transmettre efficacement la puissance disponible \u00e0 l\u2019eau. Chez ScaleMonkey, tu trouveras des h\u00e9lices s\u00e9lectionn\u00e9es pour diff\u00e9rents mod\u00e8les et concepts de propulsion. Il ne s\u2019agit pas simplement d\u2019avoir un maximum de pouss\u00e9e. Une h\u00e9lice bien accord\u00e9e doit correspondre au moteur, \u00e0 la taille et au poids du mod\u00e8le, ainsi qu\u2019au comportement recherch\u00e9.  Du mod\u00e8le scale fid\u00e8le \u00e0 l\u2019original au bateau RC orient\u00e9 performance : le bon choix d\u2019h\u00e9lice influence l\u2019acc\u00e9l\u00e9ration, la vitesse, la consommation de courant et, enfin, l\u2019allure sur l\u2019eau. Parce que la puissance ne compte que lorsqu\u2019elle arrive dans l\u2019eau.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.scalemonkey.com\/fr-be\/store\/model-building\/model-boats\/propellers\/\" \/>\n<meta property=\"og:site_name\" content=\"scalemonkey.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-be\\\/store\\\/model-building\\\/model-boats\\\/propellers\\\/\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-be\\\/store\\\/model-building\\\/model-boats\\\/propellers\\\/\",\"name\":\"H\u00e9lices-Archiv | scalemonkey.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-be\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-be\\\/store\\\/model-building\\\/model-boats\\\/propellers\\\/#breadcrumb\"},\"inLanguage\":\"fr-BE\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-be\\\/store\\\/model-building\\\/model-boats\\\/propellers\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Start\",\"item\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-be\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"H\u00e9lices\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-be\\\/#website\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-be\\\/\",\"name\":\"ScaleMonkey\",\"description\":\"Anspruchsvoller RC-Modellbau, eigene Baus\u00e4tze, Rolling-Chassis, Upgrades und Zubeh\u00f6r.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-be\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-BE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-be\\\/#organization\",\"name\":\"ScaleMonkey\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-be\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-be\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.scalemonkey.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/ScaleMonkey-mail.jpg\",\"contentUrl\":\"https:\\\/\\\/www.scalemonkey.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/ScaleMonkey-mail.jpg\",\"width\":591,\"height\":591,\"caption\":\"ScaleMonkey\"},\"image\":{\"@id\":\"https:\\\/\\\/www.scalemonkey.com\\\/fr-be\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/scalemonkey\\\/\",\"https:\\\/\\\/www.instagram.com\\\/scalemonkey\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@scalemonkeyofficial\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"H\u00e9lices-Archiv | scalemonkey.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.scalemonkey.com\/fr-be\/store\/model-building\/model-boats\/propellers\/","og_locale":"fr_FR","og_type":"article","og_title":"H\u00e9lices-Archiv | scalemonkey.com","og_description":"H\u00e9licesL\u00e0 o\u00f9 la puissance devient propulsion L\u2019h\u00e9lice est le dernier maillon de la cha\u00eene de propulsion \u2014 et l\u2019un des plus d\u00e9cisifs. Seul le bon accord entre moteur, r\u00e9gime, diam\u00e8tre d\u2019h\u00e9lice et pas permet de transmettre efficacement la puissance disponible \u00e0 l\u2019eau. Chez ScaleMonkey, tu trouveras des h\u00e9lices s\u00e9lectionn\u00e9es pour diff\u00e9rents mod\u00e8les et concepts de propulsion. Il ne s\u2019agit pas simplement d\u2019avoir un maximum de pouss\u00e9e. Une h\u00e9lice bien accord\u00e9e doit correspondre au moteur, \u00e0 la taille et au poids du mod\u00e8le, ainsi qu\u2019au comportement recherch\u00e9.  Du mod\u00e8le scale fid\u00e8le \u00e0 l\u2019original au bateau RC orient\u00e9 performance : le bon choix d\u2019h\u00e9lice influence l\u2019acc\u00e9l\u00e9ration, la vitesse, la consommation de courant et, enfin, l\u2019allure sur l\u2019eau. Parce que la puissance ne compte que lorsqu\u2019elle arrive dans l\u2019eau.","og_url":"https:\/\/www.scalemonkey.com\/fr-be\/store\/model-building\/model-boats\/propellers\/","og_site_name":"scalemonkey.com","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.scalemonkey.com\/fr-be\/store\/model-building\/model-boats\/propellers\/","url":"https:\/\/www.scalemonkey.com\/fr-be\/store\/model-building\/model-boats\/propellers\/","name":"H\u00e9lices-Archiv | scalemonkey.com","isPartOf":{"@id":"https:\/\/www.scalemonkey.com\/fr-be\/#website"},"breadcrumb":{"@id":"https:\/\/www.scalemonkey.com\/fr-be\/store\/model-building\/model-boats\/propellers\/#breadcrumb"},"inLanguage":"fr-BE"},{"@type":"BreadcrumbList","@id":"https:\/\/www.scalemonkey.com\/fr-be\/store\/model-building\/model-boats\/propellers\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Start","item":"https:\/\/www.scalemonkey.com\/fr-be\/home\/"},{"@type":"ListItem","position":2,"name":"H\u00e9lices"}]},{"@type":"WebSite","@id":"https:\/\/www.scalemonkey.com\/fr-be\/#website","url":"https:\/\/www.scalemonkey.com\/fr-be\/","name":"ScaleMonkey","description":"Anspruchsvoller RC-Modellbau, eigene Baus\u00e4tze, Rolling-Chassis, Upgrades und Zubeh\u00f6r.","publisher":{"@id":"https:\/\/www.scalemonkey.com\/fr-be\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.scalemonkey.com\/fr-be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-BE"},{"@type":"Organization","@id":"https:\/\/www.scalemonkey.com\/fr-be\/#organization","name":"ScaleMonkey","url":"https:\/\/www.scalemonkey.com\/fr-be\/","logo":{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/www.scalemonkey.com\/fr-be\/#\/schema\/logo\/image\/","url":"https:\/\/www.scalemonkey.com\/wp-content\/uploads\/2026\/08\/ScaleMonkey-mail.jpg","contentUrl":"https:\/\/www.scalemonkey.com\/wp-content\/uploads\/2026\/08\/ScaleMonkey-mail.jpg","width":591,"height":591,"caption":"ScaleMonkey"},"image":{"@id":"https:\/\/www.scalemonkey.com\/fr-be\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/scalemonkey\/","https:\/\/www.instagram.com\/scalemonkey\/","https:\/\/www.youtube.com\/@scalemonkeyofficial\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.scalemonkey.com\/fr-be\/wp-json\/wp\/v2\/product_cat\/6138","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.scalemonkey.com\/fr-be\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.scalemonkey.com\/fr-be\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/www.scalemonkey.com\/fr-be\/wp-json\/wp\/v2\/product_cat\/6135"}],"wp:post_type":[{"href":"https:\/\/www.scalemonkey.com\/fr-be\/wp-json\/wp\/v2\/product?product_cat=6138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}